{"id":96158,"date":"2019-09-18T10:50:13","date_gmt":"2019-09-18T15:50:13","guid":{"rendered":"https:\/\/centrourbano.com\/?p=96158"},"modified":"2019-09-18T12:03:48","modified_gmt":"2019-09-18T17:03:48","slug":"acciona-ve-estabilidad-mercado-residencial","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/","title":{"rendered":"Acciona ve estabilidad en mercado residencial"},"content":{"rendered":"<p><em>La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo\u00a0<\/em><!--more--><\/p>\n<p>El cambio de gobierno y la redefinici\u00f3n de nuevas pol\u00edticas, generaron un impacto en el sector inmobiliario residencial que en los \u00faltimos meses ha resentido una desaceleraci\u00f3n en las ventas, de acuerdo con Rodrigo D\u00edaz, director general de Acciona Parque Reforma.<\/p>\n<p>En conferencia de prensa tras anunciar sus intenciones de reforzar su presencia en mercados como la Ciudad de M\u00e9xico y Acapulco, as\u00ed como explorar nuevos destinos de desarrollo para el segmento residencial, el directivo explic\u00f3 que la colaboraci\u00f3n de las autoridades ha dado un respiro a los inversionistas, no s\u00f3lo en la capital sino en todo el pa\u00eds.<\/p>\n<p>\u00abEl segmento residencial se vio un poco desacelerado en los \u00faltimos meses, creo que lo que estamos viendo los desarrolladores es un reacomodo del nuevo gobierno (&#8230;)<\/p>\n<p>\u00abVemos una verdadera participaci\u00f3n en l\u00ednea con el gobierno en todos los temas, principalmente en licencia, eso ayuda a dar estabilidad a los inversionistas, el ver que los proyectos est\u00e1n caminando\u00bb, se\u00f1al\u00f3.<\/p>\n<p>En ese sentido, se\u00f1al\u00f3 que si bien las ventas del segmento residencial tambi\u00e9n se vieron muy afectadas en estos \u00faltimos meses, el papel de las nuevas administraciones ha ayudado a reactivar inversiones y a brindar certeza a los desarrolladores en el pa\u00eds.<\/p>\n<p>\u00abEstamos viendo una reencaminada de los proyectos,\u00a0a un gobierno en l\u00ednea con el segmento inmobiliario\u00a0que entiende la importancia que es todo todo segmento de la construcci\u00f3n y el sector inmobiliario, no s\u00f3lo en la Ciudad de M\u00e9xico sino a nivel nacional, eso va a hacer que el inversionista que estaba cauteloso empieza a ver transparencia\u00bb, se\u00f1al\u00f3.<\/p>\n<p><strong>Expansi\u00f3n<\/strong><\/p>\n<p>Acciona anunci\u00f3 su inter\u00e9s de reforzar su presencia en\u00a0la Ciudad de M\u00e9xico y Acapulco, adem\u00e1s de\u00a0querer expandirse geogr\u00e1ficamente hacia nuevos mercados como Playa del Carmen en la Riviera Maya, Guadalajara y el Baj\u00edo.<\/p>\n<p>\u201cLa apuesta por M\u00e9xico est\u00e1 firme, los proyectos en los que estamos invirtiendo actualmente suman alrededor de 500 millones de d\u00f3lares\u201d, detall\u00f3 el\u00a0ingeniero Rodrigo D\u00edaz \u00c1lvarez, director general de Parque Reforma.<\/p>\n<p>Destac\u00f3 que con 40 a\u00f1os de trayectoria, Acciona Parque Reforma es reconocido por proyectos como Parque Reforma en Cumbres de Santa Fe, SkyTown Insurgentes en la Ciudad de M\u00e9xico; PlayaMar Tres Cantos, Playamar Diamante y Club PlayaMar en Acapulco y Maranta Playacar en Playa del Carmen.<\/p>\n<p>\u00abEn Acapulco la inversi\u00f3n entre el 2018 y 2019 fue en el orden de 500\u00a0millones de pesos (&#8230;) En la Riviera Maya ser\u00e1n un h\u00edbrido de gente que trabaja en la Riviera, directivos de hoteles, y gente que compre vivienda para uso de largo plazo\u00bb, agreg\u00f3 D\u00edaz \u00c1lvarez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo\u00a0<\/p>\n","protected":false},"author":69,"featured_media":96161,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,12],"tags":[],"class_list":["post-96158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario","category-vivienda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acciona ve estabilidad en mercado residencial<\/title>\n<meta name=\"description\" content=\"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acciona ve estabilidad en mercado residencial\" \/>\n<meta property=\"og:description\" content=\"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-18T15:50:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-18T17:03:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquina-de-noche.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Fernando Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/\"},\"author\":{\"name\":\"Fernando Navarrete\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\"},\"headline\":\"Acciona ve estabilidad en mercado residencial\",\"datePublished\":\"2019-09-18T15:50:13+00:00\",\"dateModified\":\"2019-09-18T17:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/\"},\"wordCount\":475,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquina-de-noche.png\",\"articleSection\":[\"Inmobiliario\",\"Vivienda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/\",\"name\":\"Acciona ve estabilidad en mercado residencial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquina-de-noche.png\",\"datePublished\":\"2019-09-18T15:50:13+00:00\",\"dateModified\":\"2019-09-18T17:03:48+00:00\",\"description\":\"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquina-de-noche.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquina-de-noche.png\",\"width\":800,\"height\":600,\"caption\":\"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/acciona-ve-estabilidad-mercado-residencial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acciona ve estabilidad en mercado residencial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\",\"name\":\"Fernando Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"caption\":\"Fernando Navarrete\"},\"description\":\"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernando-navarrete\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acciona ve estabilidad en mercado residencial","description":"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/","og_locale":"es_ES","og_type":"article","og_title":"Acciona ve estabilidad en mercado residencial","og_description":"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo","og_url":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-09-18T15:50:13+00:00","article_modified_time":"2019-09-18T17:03:48+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquina-de-noche.png","type":"image\/png"}],"author":"Fernando Navarrete","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernando Navarrete","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/"},"author":{"name":"Fernando Navarrete","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb"},"headline":"Acciona ve estabilidad en mercado residencial","datePublished":"2019-09-18T15:50:13+00:00","dateModified":"2019-09-18T17:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/"},"wordCount":475,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquina-de-noche.png","articleSection":["Inmobiliario","Vivienda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/","url":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/","name":"Acciona ve estabilidad en mercado residencial","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquina-de-noche.png","datePublished":"2019-09-18T15:50:13+00:00","dateModified":"2019-09-18T17:03:48+00:00","description":"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquina-de-noche.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquina-de-noche.png","width":800,"height":600,"caption":"La inmobiliaria busca crecer y expandirse en plazas como Ciudad de M\u00e9xico, Acapulco, Riviera Maya y el Baj\u00edo"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/acciona-ve-estabilidad-mercado-residencial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Acciona ve estabilidad en mercado residencial"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb","name":"Fernando Navarrete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","caption":"Fernando Navarrete"},"description":"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.","url":"https:\/\/centrourbano.com\/revista\/author\/fernando-navarrete\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/96158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=96158"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/96158\/revisions"}],"predecessor-version":[{"id":96162,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/96158\/revisions\/96162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/96161"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=96158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=96158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=96158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}