{"id":93672,"date":"2019-07-22T09:26:10","date_gmt":"2019-07-22T14:26:10","guid":{"rendered":"https:\/\/centrourbano.com\/?p=93672"},"modified":"2019-07-22T10:30:58","modified_gmt":"2019-07-22T15:30:58","slug":"desacelera-mercado-en-rentas-de-sector-logistico","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/","title":{"rendered":"Desacelera mercado en rentas de sector log\u00edstico"},"content":{"rendered":"<p><em>En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019<\/em><!--more--><\/p>\n<p>La incertidumbre <strong>geopol\u00edtica<\/strong> y la desaceleraci\u00f3n del crecimiento econ\u00f3mico han frenado el crecimiento en rentas del<strong> mercado log\u00edstico<\/strong> en M\u00e9xico, lo que gener\u00f3 un incremento de 3.9% en rentas de Fibras Prologis durante el segundo trimestre del a\u00f1o.<\/p>\n<p>De acuerdo con Luis Guti\u00e9rrez, director general de <strong>Prologis M\u00e9xico<\/strong>, en los mercados orientados al consumo de la Ciudad de M\u00e9xico, Guadalajara y Monterrey, la demanda se desaceler\u00f3 a 3.4 millones de pies cuadrados en la primera mitad del a\u00f1o.<\/p>\n<p>Los mercados fronterizos se mantienen saludables, particularmente en <strong>Tijuana y Ciudad Ju\u00e1rez<\/strong> que reportan un crecimiento en absorci\u00f3n neta, sin embargo el directivo se\u00f1ala que se observa mayor inter\u00e9s de compa\u00f1\u00edas por expandirse en mercados fronterizos, lo que podr\u00eda aumentar la demanda.<\/p>\n<p>\u00abLa incertidumbre geopol\u00edtica y la desaceleraci\u00f3n del crecimiento econ\u00f3mico han frenado el crecimiento en rentas del mercado en M\u00e9xico. Las condiciones del mercado laboral y la brecha de producci\u00f3n positiva son vientos en popa, particularmente en el <strong>sector manufacturero<\/strong>\u00ab, enfatiz\u00f3.<\/p>\n<p>Por otro lado, la escasez de tierra en la Ciudad de M\u00e9xico y Tijuana han mantenido la oferta moderada, mientras en Ciudad Ju\u00e1rez y Reynosa, la oferta se ha frenado por la ratificaci\u00f3n del <strong>Tratado Comercial M\u00e9xico, Estados Unidos y Canad\u00e1.\u00a0<\/strong><\/p>\n<p>\u00abLa absorci\u00f3n neta en nuestros seis mercados fue de <strong>3.9 millones de pies cuadrados<\/strong> en el segundo trimestre con propiedades terminadas por poco m\u00e1s de 4.3 millones de pies cuadrados\u00bb, agreg\u00f3 el ingeniero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019<\/p>\n","protected":false},"author":69,"featured_media":85314,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-93672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desacelera mercado en rentas de sector log\u00edstico<\/title>\n<meta name=\"description\" content=\"En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desacelera mercado en rentas de sector log\u00edstico\" \/>\n<meta property=\"og:description\" content=\"En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-22T14:26:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-22T15:30:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/featured_prologis_georgetown.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/\"},\"author\":{\"name\":\"Fernando Navarrete\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\"},\"headline\":\"Desacelera mercado en rentas de sector log\u00edstico\",\"datePublished\":\"2019-07-22T14:26:10+00:00\",\"dateModified\":\"2019-07-22T15:30:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/featured_prologis_georgetown.jpg\",\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/\",\"name\":\"Desacelera mercado en rentas de sector log\u00edstico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/featured_prologis_georgetown.jpg\",\"datePublished\":\"2019-07-22T14:26:10+00:00\",\"dateModified\":\"2019-07-22T15:30:58+00:00\",\"description\":\"En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/featured_prologis_georgetown.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/featured_prologis_georgetown.jpg\",\"width\":1279,\"height\":640,\"caption\":\"A finales de 2018 el portafolio de la firma era de 200 inmuebles destinados a log\u00edstica y manufactura con un ABR de 3.3 millones de m\u00b2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/desacelera-mercado-en-rentas-de-sector-logistico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desacelera mercado en rentas de sector log\u00edstico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\",\"name\":\"Fernando Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"caption\":\"Fernando Navarrete\"},\"description\":\"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernando-navarrete\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desacelera mercado en rentas de sector log\u00edstico","description":"En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/","og_locale":"es_ES","og_type":"article","og_title":"Desacelera mercado en rentas de sector log\u00edstico","og_description":"En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-07-22T14:26:10+00:00","article_modified_time":"2019-07-22T15:30:58+00:00","og_image":[{"width":1279,"height":640,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/featured_prologis_georgetown.jpg","type":"image\/jpeg"}],"author":"Fernando Navarrete","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernando Navarrete","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/"},"author":{"name":"Fernando Navarrete","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb"},"headline":"Desacelera mercado en rentas de sector log\u00edstico","datePublished":"2019-07-22T14:26:10+00:00","dateModified":"2019-07-22T15:30:58+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/featured_prologis_georgetown.jpg","articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/","name":"Desacelera mercado en rentas de sector log\u00edstico","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/featured_prologis_georgetown.jpg","datePublished":"2019-07-22T14:26:10+00:00","dateModified":"2019-07-22T15:30:58+00:00","description":"En los mercados orientados al consumo de la CDMX, Guadalajara y Monterrey, la demanda desaceler\u00f3 a 3.4 millones de pies cuadrados en el 1S2019","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/featured_prologis_georgetown.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/featured_prologis_georgetown.jpg","width":1279,"height":640,"caption":"A finales de 2018 el portafolio de la firma era de 200 inmuebles destinados a log\u00edstica y manufactura con un ABR de 3.3 millones de m\u00b2"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/desacelera-mercado-en-rentas-de-sector-logistico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Desacelera mercado en rentas de sector log\u00edstico"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb","name":"Fernando Navarrete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","caption":"Fernando Navarrete"},"description":"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.","url":"https:\/\/centrourbano.com\/revista\/author\/fernando-navarrete\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/93672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=93672"}],"version-history":[{"count":3,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/93672\/revisions"}],"predecessor-version":[{"id":93675,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/93672\/revisions\/93675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/85314"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=93672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=93672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=93672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}