{"id":93160,"date":"2019-07-12T12:48:26","date_gmt":"2019-07-12T17:48:26","guid":{"rendered":"https:\/\/centrourbano.com\/?p=93160"},"modified":"2019-07-12T12:48:26","modified_gmt":"2019-07-12T17:48:26","slug":"btsd-vende-portafolio-industrial-en-el-centro-del-pais","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/","title":{"rendered":"BTSD vende portafolio industrial en el centro del pa\u00eds"},"content":{"rendered":"<p><em>La firma\u00a0concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos<\/em><!--more--><\/p>\n<p><strong>BTS Development<\/strong> (BTSD),\u00a0desarrolladora de <strong>activos industriales<\/strong>, concluy\u00f3 la venta de un <strong>portafolio<\/strong> de propiedades industriales en el centro del pa\u00eds con superficie rentable de <strong>1.2 millones de pies cuadrados<\/strong> construidos, como parte de su estrategia de crecimiento en los pr\u00f3ximos 5 a\u00f1os.<\/p>\n<p>La compa\u00f1\u00eda indic\u00f3 que dicha operaci\u00f3n fue realizada en conjunto con su socio inversionista <strong>PGIM<\/strong>, adem\u00e1s de una\u00a0una reserva de tierra en la parte norte de la Ciudad de M\u00e9xico, principalmente.<\/p>\n<p>\u201cCon esta operaci\u00f3n consolidamos nuestro primer ciclo de desarrollo en el sector inmobiliario industrial en el cual invertimos m\u00e1s de un mill\u00f3n de d\u00f3lares e iniciamos el segundo, en el cual planeamos inversiones por <strong>200 millones de d\u00f3lares<\/strong> en los pr\u00f3ximos cinco a\u00f1os y entrar a los mercados del Baj\u00edo y la frontera norte del pa\u00eds,\u201d coment\u00f3 <strong>Rodrigo Fern\u00e1ndez<\/strong>, director de Operaciones de BTS Development.<\/p>\n<p>BTSD ya arranc\u00f3 el primer proyecto de su segunda fase de inversiones en el parque industrial Apaseo el Grande <strong>Guanajuato.<\/strong> De acuerdo con el directivo, al cierre del primer trimestre del a\u00f1o en el sector industrial la demanda de <strong>espacios<\/strong> estuvo motivada por la expansi\u00f3n de empresas y la llegada de otras, sobre todo en los estados de la <strong>frontera norte<\/strong> del pa\u00eds.<\/p>\n<p>\u00abEn los primeros tres meses de 2019 se registr\u00f3 un crecimiento de las <strong>exportaciones<\/strong> de 5.4% y de la industria manufacturera del 6.1%, lo que empuj\u00f3 la demanda de espacios en los <strong>parques industriales<\/strong> de la frontera norte, principalmente\u00bb, indica.<\/p>\n<p>La venta de primer portafolio, realizada de manera conjunta con su socio inversionista PGIM, consiste en siete propiedades industriales, ubicadas principalmente en el centro del pa\u00eds.<\/p>\n<p>Los recursos permitir\u00e1n a BTSD continuar con su plan de crecimiento y en cinco a\u00f1os lograr la meta de tener bajo administraci\u00f3n hasta un mill\u00f3n de metros cuadrados de superficie rentable.<\/p>\n<p>Actualmente, la empresa ya tiene bajo administraci\u00f3n 660, 000 metros cuadrados de espacios de naves industriales Clase A y tiene presencia en <strong>Monterrey, Quer\u00e9taro, Lerma<\/strong> y el corredor <strong>Cuautitl\u00e1n-Tultitl\u00e1n-Tepozotl\u00e1n.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La firma\u00a0concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos<\/p>\n","protected":false},"author":69,"featured_media":90539,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-93160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BTSD vende portafolio industrial en el centro del pa\u00eds<\/title>\n<meta name=\"description\" content=\"La firma concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BTSD vende portafolio industrial en el centro del pa\u00eds\" \/>\n<meta property=\"og:description\" content=\"La firma concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-12T17:48:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2362\" \/>\n\t<meta property=\"og:image:height\" content=\"1575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/\"},\"author\":{\"name\":\"Fernando Navarrete\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\"},\"headline\":\"BTSD vende portafolio industrial en el centro del pa\u00eds\",\"datePublished\":\"2019-07-12T17:48:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/\"},\"wordCount\":381,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg\",\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/\",\"name\":\"BTSD vende portafolio industrial en el centro del pa\u00eds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg\",\"datePublished\":\"2019-07-12T17:48:26+00:00\",\"description\":\"La firma concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg\",\"width\":2362,\"height\":1575,\"caption\":\"La desarrolladora maneja el 5% del mercado industrial inmobiliario Clase A de la zona centro del pa\u00eds\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BTSD vende portafolio industrial en el centro del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\",\"name\":\"Fernando Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"caption\":\"Fernando Navarrete\"},\"description\":\"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernando-navarrete\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BTSD vende portafolio industrial en el centro del pa\u00eds","description":"La firma concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/","og_locale":"es_ES","og_type":"article","og_title":"BTSD vende portafolio industrial en el centro del pa\u00eds","og_description":"La firma concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-07-12T17:48:26+00:00","og_image":[{"width":2362,"height":1575,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg","type":"image\/jpeg"}],"author":"Fernando Navarrete","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernando Navarrete","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/"},"author":{"name":"Fernando Navarrete","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb"},"headline":"BTSD vende portafolio industrial en el centro del pa\u00eds","datePublished":"2019-07-12T17:48:26+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/"},"wordCount":381,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg","articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/","name":"BTSD vende portafolio industrial en el centro del pa\u00eds","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg","datePublished":"2019-07-12T17:48:26+00:00","description":"La firma concluy\u00f3 la venta de un portafolio de propiedades con una superficie rentable de 1.2 millones de pies cuadrados construidos","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/BTS-DEVELOPMENT-TEPOTZOTLAN-1.jpg","width":2362,"height":1575,"caption":"La desarrolladora maneja el 5% del mercado industrial inmobiliario Clase A de la zona centro del pa\u00eds"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/btsd-vende-portafolio-industrial-en-el-centro-del-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"BTSD vende portafolio industrial en el centro del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb","name":"Fernando Navarrete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","caption":"Fernando Navarrete"},"description":"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.","url":"https:\/\/centrourbano.com\/revista\/author\/fernando-navarrete\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/93160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=93160"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/93160\/revisions"}],"predecessor-version":[{"id":93163,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/93160\/revisions\/93163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/90539"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=93160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=93160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=93160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}