{"id":91618,"date":"2019-06-12T09:27:59","date_gmt":"2019-06-12T14:27:59","guid":{"rendered":"https:\/\/centrourbano.com\/?p=91618"},"modified":"2019-06-12T14:15:20","modified_gmt":"2019-06-12T19:15:20","slug":"cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/","title":{"rendered":"CDMX, entre las ciudades con m\u00e1s oficinas de coworking"},"content":{"rendered":"<p><em>El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0<\/em><!--more--><\/p>\n<p>La <strong>Ciudad de M\u00e9xico<\/strong> se encuentra en el octavo lugar del ranking de ciudades con m\u00e1s espacios de oficinas para <strong>coworking<\/strong>, con un inventario de 232,394 metros cuadrados (m\u00b2), apenas por debajo de ciudades como San Francisco y Boston.\u00a0<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image006.png\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91633 alignright\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image006-300x232.png\" alt=\"\" width=\"250\" height=\"193\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image006-300x232.png 300w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image006.png 376w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p>De acuerdo con la firma inmobiliaria <strong>CBRE M\u00e9xico<\/strong>, en la capital el mercado de oficinas para coworking u otros modelos flexibles ha ido en aumento en los \u00faltimos 10 a\u00f1os, situaci\u00f3n que ha transformado\u00a0radicalmente la forma en la que se construyen y configuran los nuevos edificios de oficinas.<\/p>\n<p>Al respecto, <strong>Yadira Torres<\/strong>,\u00a0directora de Investigaci\u00f3n de Mercados de CBRE M\u00e9xico, se\u00f1al\u00f3 que las nuevas generaciones juegan un papel importante por la forma de relacionarse en espacios de trabajo, pues buscan una mayor apertura, movilidad y conectividad en todo momento.\u00a0<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image010-1.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-91634 alignleft\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image010-1-300x234.jpg\" alt=\"\" width=\"300\" height=\"234\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image010-1-300x234.jpg 300w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/image010-1.jpg 457w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u201cConsiderar el concepto vivir, trabajar y disfrutar en un mismo espacio tiene gran importancia al momento de desarrollar, por eso hemos visto el boom de usos mixtos que comenz\u00f3 en la Ciudad de M\u00e9xico, luego en <strong>Monterrey<\/strong> y <strong>Guadalajara<\/strong>, y ahora en <strong>Quer\u00e9taro<\/strong> en el sector de oficinas\u201d, a\u00f1adi\u00f3.<\/p>\n<p>La directiva se\u00f1al\u00f3 que en este mercado hay tendencias que siguen en crecimiento como los usos mixtos y el coworking que incluyen segmentos <strong>industriales<\/strong>: \u201cNo s\u00f3lo las oficinas est\u00e1n en esta tendencia; esto es muy importante porque ha cambiado la manera en que consumimos, trabajamos y vivimos\u201d, destac\u00f3.<\/p>\n<p><strong>Espacios abiertos\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\">Eduardo Francisco Ortega, director de\u00a0Real Estate para Am\u00e9rica Latina y el Caribe\u00a0de American Express, se\u00f1al\u00f3 en el Foro \u00abEl Espacio Abierto en Oficinas, \u00bfProblema o Soluci\u00f3n?\u00bb que las oficinas deben ser flexibles para encontrar el mejor equilibrio destinado a un buen ambiente de trabajo.<\/p>\n<p style=\"font-weight: 400;\">Sin embargo aclar\u00f3 que no se trata\u00a0\u00fanicamente de\u00a0abrir espacios sin control, sino de llevar a cabo el mejor proceso de dise\u00f1o como una herramienta fundamental para el \u00e9xito de una compa\u00f1\u00eda.<\/p>\n<p style=\"font-weight: 400;\">En su oportunidad,\u00a0Eric Carre\u00f3n Camarena,\u00a0Senior Manager of Global Real Estate &amp; Workplace Strategy de\u00a0<em>Amazon<\/em>, habl\u00f3 de la experiencia de los espacios abiertos en esta firma internacional y destac\u00f3 que se deben analizar las necesidades de cada empresa para que la estrategia sea redituable.<\/p>\n<p style=\"font-weight: 400;\">Por su parte Juan Pablo Serrano, CEO de WorkPlus agreg\u00f3 que el ADN de cada empresa es distinto y de ello dependen los dise\u00f1os. A su juicio, un factor fundamental es el an\u00e1lisis profundo del tipo de empresa para detectar las necesidades espec\u00edficas de cada quien y otorgar tambi\u00e9n \u00e1reas de privacidad.<\/p>\n<p style=\"font-weight: 400;\">En su participaci\u00f3n Jorge E. Mendoza, director del despacho neoyorkino de Arquitectura Kohn Pedersen Fox, estim\u00f3 que la palabra clave en materia de espacios inmobiliarios es, flexibilidad. \u201cNo creo que el\u00a0<em>one size<\/em>\u00a0sea para todos\u201d, subray\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0<\/p>\n","protected":false},"author":69,"featured_media":82910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-91618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CDMX, entre las ciudades con m\u00e1s oficinas de coworking -<\/title>\n<meta name=\"description\" content=\"El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0 La Ciudad de M\u00e9xico se encuentra en el\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CDMX, entre las ciudades con m\u00e1s oficinas de coworking -\" \/>\n<meta property=\"og:description\" content=\"El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0 La Ciudad de M\u00e9xico se encuentra en el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-12T14:27:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-12T19:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/bancomer2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/\"},\"author\":{\"name\":\"Fernando Navarrete\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\"},\"headline\":\"CDMX, entre las ciudades con m\u00e1s oficinas de coworking\",\"datePublished\":\"2019-06-12T14:27:59+00:00\",\"dateModified\":\"2019-06-12T19:15:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/\"},\"wordCount\":493,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/bancomer2.jpg\",\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/\",\"name\":\"CDMX, entre las ciudades con m\u00e1s oficinas de coworking -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/bancomer2.jpg\",\"datePublished\":\"2019-06-12T14:27:59+00:00\",\"dateModified\":\"2019-06-12T19:15:20+00:00\",\"description\":\"El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0 La Ciudad de M\u00e9xico se encuentra en el\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/bancomer2.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/bancomer2.jpg\",\"width\":1280,\"height\":720,\"caption\":\"El 65% de oficinas inventariadas en la capital son Clase A y AAA de acuerdo con CBRE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CDMX, entre las ciudades con m\u00e1s oficinas de coworking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\",\"name\":\"Fernando Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"caption\":\"Fernando Navarrete\"},\"description\":\"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernando-navarrete\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CDMX, entre las ciudades con m\u00e1s oficinas de coworking -","description":"El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0 La Ciudad de M\u00e9xico se encuentra en el","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/","og_locale":"es_ES","og_type":"article","og_title":"CDMX, entre las ciudades con m\u00e1s oficinas de coworking -","og_description":"El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0 La Ciudad de M\u00e9xico se encuentra en el","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-06-12T14:27:59+00:00","article_modified_time":"2019-06-12T19:15:20+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/bancomer2.jpg","type":"image\/jpeg"}],"author":"Fernando Navarrete","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernando Navarrete","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/"},"author":{"name":"Fernando Navarrete","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb"},"headline":"CDMX, entre las ciudades con m\u00e1s oficinas de coworking","datePublished":"2019-06-12T14:27:59+00:00","dateModified":"2019-06-12T19:15:20+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/"},"wordCount":493,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/bancomer2.jpg","articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/","name":"CDMX, entre las ciudades con m\u00e1s oficinas de coworking -","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/bancomer2.jpg","datePublished":"2019-06-12T14:27:59+00:00","dateModified":"2019-06-12T19:15:20+00:00","description":"El coworking y los usos mixtos ofrecen a las nuevas generaciones espacios m\u00e1s flexibles para sus necesidades\u00a0 La Ciudad de M\u00e9xico se encuentra en el","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/bancomer2.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/bancomer2.jpg","width":1280,"height":720,"caption":"El 65% de oficinas inventariadas en la capital son Clase A y AAA de acuerdo con CBRE"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cdmx-entre-las-ciudades-con-mas-oficinas-de-coworking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"CDMX, entre las ciudades con m\u00e1s oficinas de coworking"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb","name":"Fernando Navarrete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","caption":"Fernando Navarrete"},"description":"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.","url":"https:\/\/centrourbano.com\/revista\/author\/fernando-navarrete\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/91618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=91618"}],"version-history":[{"count":6,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/91618\/revisions"}],"predecessor-version":[{"id":91652,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/91618\/revisions\/91652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/82910"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=91618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=91618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=91618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}