{"id":91492,"date":"2019-06-11T09:35:32","date_gmt":"2019-06-11T14:35:32","guid":{"rendered":"https:\/\/centrourbano.com\/?p=91492"},"modified":"2019-06-11T09:35:32","modified_gmt":"2019-06-11T14:35:32","slug":"esquema-autos-compartidos-cdmx-2020","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/","title":{"rendered":"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020"},"content":{"rendered":"<p><em>El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica<\/em><!--more--><\/p>\n<p>De acuerdo con diversos estudios, <strong>la Ciudad de M\u00e9xico es una de las urbes con m\u00e1s congestionamientos viales del mundo<\/strong>, adem\u00e1s de que los autom\u00f3viles son la principal fuente de contaminaci\u00f3n atmosf\u00e9rica.<\/p>\n<p>Por esta raz\u00f3n, <strong>el Gobierno de la Ciudad de M\u00e9xico present\u00f3 varias medidas, con las que pretende mejorar la movilidad y reducir la contaminaci\u00f3n derivada de los congestionamientos viales<\/strong>, que incluyen la restricci\u00f3n a la circulaci\u00f3n de veh\u00edculos que tengan placas de otros Estados, la creaci\u00f3n de una mejor red de transporte p\u00fablico y un<strong> esquema de autos compartidos.<\/strong><\/p>\n<p>Esta \u00faltima busca la <strong>implementaci\u00f3n de viajes compartidos en autom\u00f3viles privados en las v\u00edas de acceso controlados de la CDMX,<\/strong> es decir avenidas primarias cuyas intersecciones son generalmente a desnivel, cuentan con carriles centrales y est\u00e1n separados por camellones. Esta medida<strong> entrar\u00e1 en vigor en 2020 y ser\u00e1 obligatoria de las 7 a las 10 de la ma\u00f1ana<\/strong>, horarios en los que se presentan m\u00e1s congestionamientos.<\/p>\n<p>El <strong>titular de la Secretar\u00eda de Movilidad de la Ciudad de M\u00e9xico (Semovi), Andr\u00e9s Lajous<\/strong>, explic\u00f3 que se busca que en estas vialidades haya un carril de alta velocidad, al que solo podr\u00e1n incorporarse autos con dos o m\u00e1s pasajeros. \u201cEl reto de la movilidad es que muchas personas nos movemos en la misma direcci\u00f3n a la misma hora\u201d, agreg\u00f3.<\/p>\n<p>Lajous se\u00f1al\u00f3 que, para que este esquema entre en vigor<strong> se necesitar\u00e1n c\u00e1maras de vigilancia y agentes de tr\u00e1nsito que verifiquen que solo autos compartidos circulen por estos carriles<\/strong>, y expres\u00f3 que las sanciones para las personas que incumplan con esta medida, as\u00ed como las vialidades en las que se implementar\u00e1 y otros aspectos, est\u00e1n a\u00fan por definirse.<\/p>\n<p>El esquema de autos compartidos ha sido objeto de cr\u00edticas por parte de los ciudadanos, pues, aunque se ha implementado en muchas otras ciudades del mundo, <strong>la evidencia sobre su efectividad a lo largo del tiempo no es muy favorable<\/strong>, pues los usuarios encuentran maneras de infringir la ley.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica<\/p>\n","protected":false},"author":73,"featured_media":91497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[82],"tags":[15797,1828,15798,15617],"class_list":["post-91492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urbanismo","tag-automoviles-compartidos","tag-gobierno-de-la-ciudad-de-mexico","tag-plan-de-reduccion-de-emisiones","tag-secretaria-de-movilidad-de-la-ciudad-de-mexico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020<\/title>\n<meta name=\"description\" content=\"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020\" \/>\n<meta property=\"og:description\" content=\"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-11T14:35:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nannz_Hernandez\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/\"},\"author\":{\"name\":\"Fernanda Hern\u00e1ndez\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/9243fdb6807c0fed168f58712aef7db1\"},\"headline\":\"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020\",\"datePublished\":\"2019-06-11T14:35:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/\"},\"wordCount\":385,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg\",\"keywords\":[\"Autom\u00f3viles Compartidos\",\"Gobierno de la ciudad de M\u00e9xico\",\"Plan de reducci\u00f3n de emisiones\",\"Secretar\u00eda de Movilidad de la Ciudad de M\u00e9xico\"],\"articleSection\":[\"Urbanismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/\",\"name\":\"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg\",\"datePublished\":\"2019-06-11T14:35:32+00:00\",\"description\":\"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg\",\"width\":720,\"height\":540,\"caption\":\"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/esquema-autos-compartidos-cdmx-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/9243fdb6807c0fed168f58712aef7db1\",\"name\":\"Fernanda Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"caption\":\"Fernanda Hern\u00e1ndez\"},\"description\":\"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nannz_Hernandez\"],\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernanda-hernandez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020","description":"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/","og_locale":"es_ES","og_type":"article","og_title":"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020","og_description":"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica","og_url":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-06-11T14:35:32+00:00","og_image":[{"width":720,"height":540,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg","type":"image\/jpeg"}],"author":"Fernanda Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nannz_Hernandez","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernanda Hern\u00e1ndez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/"},"author":{"name":"Fernanda Hern\u00e1ndez","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/9243fdb6807c0fed168f58712aef7db1"},"headline":"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020","datePublished":"2019-06-11T14:35:32+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/"},"wordCount":385,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg","keywords":["Autom\u00f3viles Compartidos","Gobierno de la ciudad de M\u00e9xico","Plan de reducci\u00f3n de emisiones","Secretar\u00eda de Movilidad de la Ciudad de M\u00e9xico"],"articleSection":["Urbanismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/","url":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/","name":"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg","datePublished":"2019-06-11T14:35:32+00:00","description":"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Esquema-de-autos-compartidos-entrar\u00e1-en-vigor-en-la-CDMX-en-2020.jpg","width":720,"height":540,"caption":"El esquema de autos compartidos forma parte de las medidas del Gobierno capitalino para reducir la contaminaci\u00f3n atmosf\u00e9rica"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/esquema-autos-compartidos-cdmx-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Esquema de autos compartidos entrar\u00e1 en vigor en la CDMX en 2020"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/9243fdb6807c0fed168f58712aef7db1","name":"Fernanda Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","caption":"Fernanda Hern\u00e1ndez"},"description":"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Nannz_Hernandez"],"url":"https:\/\/centrourbano.com\/revista\/author\/fernanda-hernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/91492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=91492"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/91492\/revisions"}],"predecessor-version":[{"id":91498,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/91492\/revisions\/91498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/91497"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=91492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=91492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=91492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}