{"id":88631,"date":"2019-04-09T14:12:12","date_gmt":"2019-04-09T19:12:12","guid":{"rendered":"https:\/\/centrourbano.com\/?p=88631"},"modified":"2019-04-09T14:46:39","modified_gmt":"2019-04-09T19:46:39","slug":"fovissste-crecimiento-cartera","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/","title":{"rendered":"Cartera de cr\u00e9dito de Fovissste crecer\u00eda hasta 9%"},"content":{"rendered":"<p><em>La agencia asegur\u00f3 que el organismo hipotecario cuenta con solidez financiera para hacer frente a sus obligaciones <\/em><!--more--><\/p>\n<p>La agencia internacional <strong>Standard &amp; Poor\u2019s (S&amp;P) Global Ratings<\/strong> estim\u00f3 que, en los pr\u00f3ximos dos a\u00f1os, la cartera de cr\u00e9dito de <strong>Fovissste<\/strong> podr\u00eda crecer en promedio hasta 9%; adem\u00e1s, expuso que para 2019 y 2020, se espera que el organismo hipotecario obtenga retornos sobre activos del orden de 4 por ciento.<\/p>\n<p>Al emitir su reporte de evaluaci\u00f3n, en donde la firma ratific\u00f3 la perspectiva estable y las m\u00e1ximas calificaciones crediticias a escala nacional para Fovissste, S&amp;P se\u00f1al\u00f3 que el Fondo cuenta con <strong>fortaleza financiera<\/strong>. En especial, dijo que el Fondo mantiene en su balance un nivel de liquidez \u00f3ptimo para cumplir con sus obligaciones y metas de colocaci\u00f3n.<\/p>\n<p>\u201cConsideramos que la liquidez del Fovissste es suficiente para cumplir con sus obligaciones crediticias debido a la naturaleza de largo plazo de sus pasivos. Adem\u00e1s, en nuestra opini\u00f3n, sus sistemas de manejo de liquidez son adecuados para dar seguimiento a las entradas y salidas de efectivo, y no hay concentraciones de pasivos que pudieran comprometer la liquidez de la entidad en el corto plazo\u201d, afirm\u00f3 la agencia.<\/p>\n<p>A decir de S&amp;P, las calificaciones otorgadas al Fondo, \u201creflejan su s\u00f3lida estabilidad de negocio\u201d. En el documento, la agencia indic\u00f3 que el organismo est\u00e1 preparado para cualquier escenario. Incluso, dijo, cuenta con <strong>reservas<\/strong> que cubren cuatro veces su cartera <strong>vencida<\/strong>.<\/p>\n<p>[quote]\u201cIncluso en un \u2018escenario de estr\u00e9s\u2019el Fondo de Vivienda seguir\u00eda presentando flujos positivos gracias a la capacidad de realizar titulizaciones en el mercado (\u2026) adem\u00e1s de que tiene un fondeo estable de largo plazo y niveles s\u00f3lidos de liquidez que respaldan sus operaciones diarias\u201d, se\u00f1al\u00f3.[\/quote]<\/p>\n<p>La agencia destac\u00f3 que el Fondo ha iniciado un proceso de mejora operativo. Manifest\u00f3 que estas acciones permitir\u00e1n al organismo obtener m\u00e1rgenes importantes.<\/p>\n<p>\u201cBajo un escenario base, S&amp;P Global Ratings proyect\u00f3 para el Fovissste un crecimiento promedio de la cartera de cr\u00e9dito de 9 por ciento para los pr\u00f3ximos dos a\u00f1os, as\u00ed como reservas para p\u00e9rdidas no esperadas con tendencia al alza y p\u00e9rdidas crediticias menores al 2 por ciento del total de la cartera.<\/p>\n<p>\u201cEl Fondo tendr\u00e1 retorno a activos en aproximadamente 4 por ciento en 2019 y 2020 derivado de un margen neto de intereses y mejoras a niveles en eficiencia de alrededor de 6 por ciento, en ambos casos, como resultado de mayor eficiencia en el manejo de gastos administrativos\u201d, expuso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La agencia asegur\u00f3 que el organismo hipotecario cuenta con solidez financiera para hacer frente a sus obligaciones<\/p>\n","protected":false},"author":47,"featured_media":78096,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[12],"tags":[14718,173,155,10579,13700,60],"class_list":["post-88631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivienda","tag-cartera-de-credito","tag-credito","tag-fovissste","tag-sp","tag-solidez-financiera","tag-vivienda-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estima S&amp;P crecimiento de 9% en la cartera de cr\u00e9dito de Fovissste<\/title>\n<meta name=\"description\" content=\"La agencia internacional Standard &amp; Poor\u2019s (S&amp;P) Global Ratings estim\u00f3 que, en los pr\u00f3ximos dos a\u00f1os, la cartera de cr\u00e9dito de Fovissste...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estima S&amp;P crecimiento de 9% en la cartera de cr\u00e9dito de Fovissste\" \/>\n<meta property=\"og:description\" content=\"La agencia internacional Standard &amp; Poor\u2019s (S&amp;P) Global Ratings estim\u00f3 que, en los pr\u00f3ximos dos a\u00f1os, la cartera de cr\u00e9dito de Fovissste...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-09T19:12:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-09T19:46:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/fovissste-5-e1536765483149.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edgar Rosas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ERosasCU?s=09\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edgar Rosas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/\"},\"author\":{\"name\":\"Edgar Rosas\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/5884f91493ad1028eb55261dff64e770\"},\"headline\":\"Cartera de cr\u00e9dito de Fovissste crecer\u00eda hasta 9%\",\"datePublished\":\"2019-04-09T19:12:12+00:00\",\"dateModified\":\"2019-04-09T19:46:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/fovissste-5-e1536765483149.jpg\",\"keywords\":[\"Cartera de cr\u00e9dito\",\"cr\u00e9dito\",\"Fovissste\",\"S&amp;P\",\"Solidez financiera\",\"vivienda\"],\"articleSection\":[\"Vivienda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/\",\"name\":\"Estima S&P crecimiento de 9% en la cartera de cr\u00e9dito de Fovissste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/fovissste-5-e1536765483149.jpg\",\"datePublished\":\"2019-04-09T19:12:12+00:00\",\"dateModified\":\"2019-04-09T19:46:39+00:00\",\"description\":\"La agencia internacional Standard & Poor\u2019s (S&P) Global Ratings estim\u00f3 que, en los pr\u00f3ximos dos a\u00f1os, la cartera de cr\u00e9dito de Fovissste...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/fovissste-5-e1536765483149.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/fovissste-5-e1536765483149.jpg\",\"width\":1200,\"height\":663,\"caption\":\"Desde el lanzamiento de Fovissste Digital se han registrado 584 movimientos de pago con d\u00e9bito y cr\u00e9dito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/fovissste-crecimiento-cartera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartera de cr\u00e9dito de Fovissste crecer\u00eda hasta 9%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/5884f91493ad1028eb55261dff64e770\",\"name\":\"Edgar Rosas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g\",\"caption\":\"Edgar Rosas\"},\"description\":\"Editor en Jefe de Centro Urbano. Egresado de la maestr\u00eda en Periodismo Pol\u00edtico de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda (EPCSG). Estudi\u00f3 la licenciatura en Comunicaci\u00f3n en la Universidad Mexicana. Amante de la cr\u00f3nica y el reportaje. Admirador de Vicente Le\u00f1ero y Miguel \u00c1ngel Granados Chapa.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ERosasCU?s=09\"],\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/edgar-rosas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estima S&P crecimiento de 9% en la cartera de cr\u00e9dito de Fovissste","description":"La agencia internacional Standard & Poor\u2019s (S&P) Global Ratings estim\u00f3 que, en los pr\u00f3ximos dos a\u00f1os, la cartera de cr\u00e9dito de Fovissste...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/","og_locale":"es_ES","og_type":"article","og_title":"Estima S&P crecimiento de 9% en la cartera de cr\u00e9dito de Fovissste","og_description":"La agencia internacional Standard & Poor\u2019s (S&P) Global Ratings estim\u00f3 que, en los pr\u00f3ximos dos a\u00f1os, la cartera de cr\u00e9dito de Fovissste...","og_url":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-04-09T19:12:12+00:00","article_modified_time":"2019-04-09T19:46:39+00:00","og_image":[{"width":1200,"height":663,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/fovissste-5-e1536765483149.jpg","type":"image\/jpeg"}],"author":"Edgar Rosas","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ERosasCU?s=09","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Edgar Rosas","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/"},"author":{"name":"Edgar Rosas","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/5884f91493ad1028eb55261dff64e770"},"headline":"Cartera de cr\u00e9dito de Fovissste crecer\u00eda hasta 9%","datePublished":"2019-04-09T19:12:12+00:00","dateModified":"2019-04-09T19:46:39+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/fovissste-5-e1536765483149.jpg","keywords":["Cartera de cr\u00e9dito","cr\u00e9dito","Fovissste","S&amp;P","Solidez financiera","vivienda"],"articleSection":["Vivienda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/","url":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/","name":"Estima S&P crecimiento de 9% en la cartera de cr\u00e9dito de Fovissste","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/fovissste-5-e1536765483149.jpg","datePublished":"2019-04-09T19:12:12+00:00","dateModified":"2019-04-09T19:46:39+00:00","description":"La agencia internacional Standard & Poor\u2019s (S&P) Global Ratings estim\u00f3 que, en los pr\u00f3ximos dos a\u00f1os, la cartera de cr\u00e9dito de Fovissste...","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/fovissste-5-e1536765483149.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/fovissste-5-e1536765483149.jpg","width":1200,"height":663,"caption":"Desde el lanzamiento de Fovissste Digital se han registrado 584 movimientos de pago con d\u00e9bito y cr\u00e9dito"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/fovissste-crecimiento-cartera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Cartera de cr\u00e9dito de Fovissste crecer\u00eda hasta 9%"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/5884f91493ad1028eb55261dff64e770","name":"Edgar Rosas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g","caption":"Edgar Rosas"},"description":"Editor en Jefe de Centro Urbano. Egresado de la maestr\u00eda en Periodismo Pol\u00edtico de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda (EPCSG). Estudi\u00f3 la licenciatura en Comunicaci\u00f3n en la Universidad Mexicana. Amante de la cr\u00f3nica y el reportaje. Admirador de Vicente Le\u00f1ero y Miguel \u00c1ngel Granados Chapa.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/ERosasCU?s=09"],"url":"https:\/\/centrourbano.com\/revista\/author\/edgar-rosas\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/88631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=88631"}],"version-history":[{"count":4,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/88631\/revisions"}],"predecessor-version":[{"id":88639,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/88631\/revisions\/88639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/78096"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=88631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=88631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=88631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}