{"id":87125,"date":"2019-02-28T18:24:04","date_gmt":"2019-03-01T00:24:04","guid":{"rendered":"https:\/\/centrourbano.com\/?p=87125"},"modified":"2019-02-28T18:25:01","modified_gmt":"2019-03-01T00:25:01","slug":"cushman-wakefield-expande-presencia-en-tijuana","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/","title":{"rendered":"Cushman &#038; Wakefield expande presencia en Tijuana"},"content":{"rendered":"<p><em>Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales\u00a0<\/em><!--more--><\/p>\n<p>La consultora inmobiliaria Cushman &amp; Wakefield reforz\u00f3\u00a0sus\u00a0operaciones en Tijuana con la incorporaci\u00f3n de Rafael Garc\u00eda Rovirosa y Juan Carlos Rodr\u00edguez Velasco como directores de oficina en la ciudad fronteriza desde el mes de enero.<\/p>\n<p>\u00abLas condiciones del mercado nacional pueden parecer inciertas, sin embargo, escenarios como el actual motivan la nuestros clientes en la b\u00fasqueda de un asesor experto para la toma de decisiones en negocios (&#8230;)<\/p>\n<p>Tijuana es un mercado s\u00f3lido y creciente en donde vemos gran oportunidad de desarrollo para nuestros clientes\u00bb, destaca la firma de corretaje en un comunicado.<\/p>\n<p>La empresa destaca que actualmente Tijuana es un mercado a la vanguardia de la actividad industrial, que cuenta con m\u00e1s de 7 millones de metros cuadrados (m\u00b2) rentables y con un creciente rol en el mercado de oficinas tambi\u00e9n, al que se han sumado alrededor de 150,000 m\u00b2 en los \u00faltimos tres a\u00f1os.<\/p>\n<p>Foto: The Raws<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales\u00a0<\/p>\n","protected":false},"author":69,"featured_media":87128,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-87125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cushman &amp; Wakefield expande presencia en Tijuana<\/title>\n<meta name=\"description\" content=\"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cushman &amp; Wakefield expande presencia en Tijuana\" \/>\n<meta property=\"og:description\" content=\"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-01T00:24:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-01T00:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/03-2-e1551399739994.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Navarrete\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Navarrete\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/\"},\"author\":{\"name\":\"Fernando Navarrete\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\"},\"headline\":\"Cushman &#038; Wakefield expande presencia en Tijuana\",\"datePublished\":\"2019-03-01T00:24:04+00:00\",\"dateModified\":\"2019-03-01T00:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/\"},\"wordCount\":172,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/03-2-e1551399739994.jpg\",\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/\",\"name\":\"Cushman & Wakefield expande presencia en Tijuana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/03-2-e1551399739994.jpg\",\"datePublished\":\"2019-03-01T00:24:04+00:00\",\"dateModified\":\"2019-03-01T00:25:01+00:00\",\"description\":\"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/03-2-e1551399739994.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/03-2-e1551399739994.jpg\",\"width\":750,\"height\":421,\"caption\":\"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/cushman-wakefield-expande-presencia-en-tijuana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cushman &#038; Wakefield expande presencia en Tijuana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/336f6f6d9e77134594948411d69353fb\",\"name\":\"Fernando Navarrete\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g\",\"caption\":\"Fernando Navarrete\"},\"description\":\"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernando-navarrete\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cushman & Wakefield expande presencia en Tijuana","description":"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/","og_locale":"es_ES","og_type":"article","og_title":"Cushman & Wakefield expande presencia en Tijuana","og_description":"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-03-01T00:24:04+00:00","article_modified_time":"2019-03-01T00:25:01+00:00","og_image":[{"width":750,"height":421,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/03-2-e1551399739994.jpg","type":"image\/jpeg"}],"author":"Fernando Navarrete","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernando Navarrete","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/"},"author":{"name":"Fernando Navarrete","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb"},"headline":"Cushman &#038; Wakefield expande presencia en Tijuana","datePublished":"2019-03-01T00:24:04+00:00","dateModified":"2019-03-01T00:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/"},"wordCount":172,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/03-2-e1551399739994.jpg","articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/","name":"Cushman & Wakefield expande presencia en Tijuana","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/03-2-e1551399739994.jpg","datePublished":"2019-03-01T00:24:04+00:00","dateModified":"2019-03-01T00:25:01+00:00","description":"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/03-2-e1551399739994.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/03-2-e1551399739994.jpg","width":750,"height":421,"caption":"Tijuana cuenta con 7 millones de metros cuadrados rentables de espacios industriales"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/cushman-wakefield-expande-presencia-en-tijuana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Cushman &#038; Wakefield expande presencia en Tijuana"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/336f6f6d9e77134594948411d69353fb","name":"Fernando Navarrete","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4dd6927a99e72698473e350e20ec8a38bd48cb668e15b03d04e8e537da41ad0?s=96&d=mm&r=g","caption":"Fernando Navarrete"},"description":"Reportero de negocios, inmobiliario, construcci\u00f3n e industria. Me interesa la econom\u00eda, pol\u00edtica, historia y antropolog\u00eda. Estudi\u00e9 en la Facultad de Ciencias Pol\u00edticas y Sociales de la UNAM. Tengo experiencia en el sector p\u00fablico, la industria del acero, ingenier\u00eda civil, IT y corporativos; soy un nost\u00e1lgico nacionalista contempor\u00e1neo que cree en la grandeza de su pa\u00eds. Asiduo lector de Juan Rulfo, Jos\u00e9 Revueltas y J. R. R Tolkien.","url":"https:\/\/centrourbano.com\/revista\/author\/fernando-navarrete\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/87125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=87125"}],"version-history":[{"count":2,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/87125\/revisions"}],"predecessor-version":[{"id":87130,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/87125\/revisions\/87130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/87128"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=87125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=87125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=87125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}