{"id":84240,"date":"2019-01-07T12:24:56","date_gmt":"2019-01-07T18:24:56","guid":{"rendered":"https:\/\/centrourbano.com\/?p=84240"},"modified":"2019-01-07T13:22:38","modified_gmt":"2019-01-07T19:22:38","slug":"azcapotzalco-cierra-ventanilla-enero","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/","title":{"rendered":"Azcapotzalco cierra ventanilla para desarrollos"},"content":{"rendered":"<p><em>La medida fue publicada en la Gaceta Oficial este lunes 7 de enero<\/em><!--more--><\/p>\n<p>En lo que resta del mes de enero, la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registros de manifestaciones de obra tipo &#8216;C&#8217;-en su modalidad de obra nueva-quedan suspendidos en la alcald\u00eda de <strong>Azcapotzalco<\/strong>.<\/p>\n<p>As\u00ed se public\u00f3 este lunes en <strong>Gaceta Oficial de la Ciudad de M\u00e9xico<\/strong>, con lo que la suspensi\u00f3n se mantiene y liga su tercer mes. A trav\u00e9s del acuerdo emitido por las autoridades de la alcald\u00eda se argumenta que la decisi\u00f3n se toma \u201ctoda vez que las consideraciones que motivaron tales suspensiones contin\u00faan vigentes\u201d.<\/p>\n<blockquote><p>Acuerdo por el que se suspenden temporalmente los t\u00e9rminos para la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registro de manifestaciones de construcci\u00f3n tipo c en su modalidad de obra nueva en la coordinaci\u00f3n de ventanilla \u00fanica de la alcald\u00eda en Azcapotzalco.<\/p><\/blockquote>\n<p>A la letra, el documento establece que \u201cconsiderando que con fechas 17 de octubre y 3 de diciembre de 2018, esta Alcald\u00eda public\u00f3 en la Gaceta Oficial de la Ciudad de M\u00e9xico, Acuerdos por los que se suspenden t\u00e9rminos para la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y obras en la Coordinaci\u00f3n de Ventanilla \u00danica de la Alcald\u00eda en Azcapotzalco, y toda vez que las consideraciones que motivaron tales suspensiones contin\u00faan <strong>vigentes<\/strong>\u201d, se posterga la suspensi\u00f3n.<\/p>\n<p>El acuerdo fue firmado por el alcalde <strong>Vidal Llerena Morales<\/strong> y entra en vigor este mismo lunes.<\/p>\n<blockquote><p>\u00abSe declaran como inh\u00e1biles los d\u00edas 7, 8, 9, 10, 11, 14, 15, 16, 17, 18, 21, 22, 23, 24, 25, 28, 29, 30 y 31 de enero de 2019 para la pr\u00e1ctica de actuaciones y diligencias en los procedimientos administrativos que se desarrollan ante la Coordinaci\u00f3n de Ventanilla \u00danica de la Alcald\u00eda en Azcapotzalco en relaci\u00f3n con los ingresos de registros de Manifestaci\u00f3n de Construcci\u00f3n Tipo C en su modalidad de obra nueva, como son, de manera enunciativa mas no limitativa, la recepci\u00f3n de documentos e informes, la realizaci\u00f3n de tr\u00e1mites, actuaciones o diligencias, la emisi\u00f3n de resoluciones o acuerdos, inicio, substanciaci\u00f3n, desahogo de procedimientos administrativos, notificaciones, citatorios, emplazamientos, requerimientos, solicitudes de informes o documentos, recursos de inconformidad o alg\u00fan otro medio de impugnaci\u00f3n, as\u00ed como cualquier acto administrativo emitido por los servicios p\u00fablicos adscritos a la Coordinaci\u00f3n de Ventanilla \u00danica de esta Alcald\u00eda en relaci\u00f3n con ingresos de registros de Manifestaci\u00f3n de Construcci\u00f3n Tipo C en su modalidad de obra nueva\u00bb, destaca el escrito.<\/p><\/blockquote>\n<p style=\"text-align: center;\"><em><strong>Te podr\u00eda interesar:<\/strong><\/em><\/p>\n<a href=\"https:\/\/centrourbano.com\/2018\/12\/27\/extiende-seduvi-suspension-norma-26\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-84245\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Extienden-suspensi\u00f3n-Norma-26_Nota.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Extienden-suspensi\u00f3n-Norma-26_Nota.jpg 604w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Extienden-suspensi\u00f3n-Norma-26_Nota-300x225.jpg 300w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Extienden-suspensi\u00f3n-Norma-26_Nota-100x75.jpg 100w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>\n","protected":false},"excerpt":{"rendered":"<p>La medida fue publicada en la Gaceta Oficial este lunes 7 de enero<\/p>\n","protected":false},"author":47,"featured_media":79008,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15,12],"tags":[1098,15113,278,1672,15114,60],"class_list":["post-84240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario","category-vivienda","tag-azcapotzalco","tag-cierre","tag-desarrollos","tag-ventanilla","tag-vidal-llerena-morales","tag-vivienda-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Azcapotzalco cierra ventanilla para tr\u00e1mites de construcci\u00f3n<\/title>\n<meta name=\"description\" content=\"En lo que resta del mes de enero, la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registros de y registro de manifestaciones...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Azcapotzalco cierra ventanilla para tr\u00e1mites de construcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"En lo que resta del mes de enero, la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registros de y registro de manifestaciones...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-07T18:24:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-07T19:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Edgar Rosas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ERosasCU?s=09\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edgar Rosas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/\"},\"author\":{\"name\":\"Edgar Rosas\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c19daead84933d83247e0b386a878d10\"},\"headline\":\"Azcapotzalco cierra ventanilla para desarrollos\",\"datePublished\":\"2019-01-07T18:24:56+00:00\",\"dateModified\":\"2019-01-07T19:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/\"},\"wordCount\":442,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg\",\"keywords\":[\"Azcapotzalco\",\"cierre\",\"desarrollos\",\"ventanilla\",\"Vidal Llerena Morales\",\"vivienda\"],\"articleSection\":[\"Inmobiliario\",\"Vivienda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/\",\"name\":\"Azcapotzalco cierra ventanilla para tr\u00e1mites de construcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg\",\"datePublished\":\"2019-01-07T18:24:56+00:00\",\"dateModified\":\"2019-01-07T19:22:38+00:00\",\"description\":\"En lo que resta del mes de enero, la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registros de y registro de manifestaciones...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg\",\"width\":800,\"height\":450,\"caption\":\"Esta zona se mantiene firme gracias al segmento usado y al mercado en la Roma Norte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/azcapotzalco-cierra-ventanilla-enero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Azcapotzalco cierra ventanilla para desarrollos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c19daead84933d83247e0b386a878d10\",\"name\":\"Edgar Rosas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g\",\"caption\":\"Edgar Rosas\"},\"description\":\"Editor en Jefe de Centro Urbano. Egresado de la maestr\u00eda en Periodismo Pol\u00edtico de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda (EPCSG). Estudi\u00f3 la licenciatura en Comunicaci\u00f3n en la Universidad Mexicana. Amante de la cr\u00f3nica y el reportaje. Admirador de Vicente Le\u00f1ero y Miguel \u00c1ngel Granados Chapa.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ERosasCU?s=09\"],\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/edgar-rosas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Azcapotzalco cierra ventanilla para tr\u00e1mites de construcci\u00f3n","description":"En lo que resta del mes de enero, la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registros de y registro de manifestaciones...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/","og_locale":"es_ES","og_type":"article","og_title":"Azcapotzalco cierra ventanilla para tr\u00e1mites de construcci\u00f3n","og_description":"En lo que resta del mes de enero, la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registros de y registro de manifestaciones...","og_url":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2019-01-07T18:24:56+00:00","article_modified_time":"2019-01-07T19:22:38+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg","type":"image\/jpeg"}],"author":"Edgar Rosas","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ERosasCU?s=09","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Edgar Rosas","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/"},"author":{"name":"Edgar Rosas","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c19daead84933d83247e0b386a878d10"},"headline":"Azcapotzalco cierra ventanilla para desarrollos","datePublished":"2019-01-07T18:24:56+00:00","dateModified":"2019-01-07T19:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/"},"wordCount":442,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg","keywords":["Azcapotzalco","cierre","desarrollos","ventanilla","Vidal Llerena Morales","vivienda"],"articleSection":["Inmobiliario","Vivienda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/","url":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/","name":"Azcapotzalco cierra ventanilla para tr\u00e1mites de construcci\u00f3n","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg","datePublished":"2019-01-07T18:24:56+00:00","dateModified":"2019-01-07T19:22:38+00:00","description":"En lo que resta del mes de enero, la recepci\u00f3n de tr\u00e1mites y procedimientos en materia de construcciones y registros de y registro de manifestaciones...","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/vivienda-plus-inmobiliare-amenidades-atractivo-compradores-desarrollos-e1549902561134.jpeg","width":800,"height":450,"caption":"Esta zona se mantiene firme gracias al segmento usado y al mercado en la Roma Norte"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/azcapotzalco-cierra-ventanilla-enero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Azcapotzalco cierra ventanilla para desarrollos"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c19daead84933d83247e0b386a878d10","name":"Edgar Rosas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/94440c4283495211faa5300bf85e80061036b83fced868c3783aa1310b350d9c?s=96&d=mm&r=g","caption":"Edgar Rosas"},"description":"Editor en Jefe de Centro Urbano. Egresado de la maestr\u00eda en Periodismo Pol\u00edtico de la Escuela de Periodismo Carlos Septi\u00e9n Garc\u00eda (EPCSG). Estudi\u00f3 la licenciatura en Comunicaci\u00f3n en la Universidad Mexicana. Amante de la cr\u00f3nica y el reportaje. Admirador de Vicente Le\u00f1ero y Miguel \u00c1ngel Granados Chapa.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/ERosasCU?s=09"],"url":"https:\/\/centrourbano.com\/revista\/author\/edgar-rosas\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/84240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=84240"}],"version-history":[{"count":5,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/84240\/revisions"}],"predecessor-version":[{"id":84260,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/84240\/revisions\/84260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/79008"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=84240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=84240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=84240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}