{"id":48729,"date":"2017-02-10T09:32:10","date_gmt":"2017-02-10T15:32:10","guid":{"rendered":"https:\/\/centrourbano.com\/?p=48729"},"modified":"2017-02-10T09:36:05","modified_gmt":"2017-02-10T15:36:05","slug":"soriana-construira-2-tiendas-en-zacatecas","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/","title":{"rendered":"Soriana construir\u00e1 2 tiendas en Zacatecas"},"content":{"rendered":"<p><em>A\u00fan est\u00e1 por definirse el formato de tienda que se establecer\u00eda para iniciar operaciones en 2018<\/em><br \/>\n<!--more--><\/p>\n<p>Ricardo Mart\u00edn Bringas, director general de Organizaci\u00f3n Soriana, anunci\u00f3 que la empresa planea el desarrollo de dos tiendas en Zacatecas, aunque todav\u00eda no se define el formato, aunque la inversi\u00f3n planeada es de unos 250,000,000 de pesos para iniciar operaciones el pr\u00f3ximo a\u00f1o. <\/p>\n<p>Esto lo declar\u00f3 despu\u00e9s de reunirse con el gobernador de la entidad, Alejandro Tello y el secretario de Econom\u00eda, Carlos B\u00e1rcena, en donde acordaron la instalaci\u00f3n de las dos tiendas.  <\/p>\n<p>\u201cEl gobierno ha mostrado total apertura para que empresarios lleguen a instalarse: afortunadamente nos abri\u00f3 las puertas del estado y da las facilidades par que, sin ning\u00fan problema, podamos invertir en la regi\u00f3n. Estas 2 tiendas generar\u00edan un promedio de 1,000 nuevos empleos, entre 650 y 750 directos y 250 indirectos\u201d, abund\u00f3 el empresario. <\/p>\n<p>Dijo que en la entidad hay oportunidad de establecer formatos de tienda que no hay actualmente, como es el Club de Precios y \u00e9se se podr\u00eda impulsar, o bien, el formato de Soriana expr\u00e9s, que ya se tiene en cuatro municipios, pero se podr\u00eda llevar a otros municipios peque\u00f1os.<\/p>\n<p>Para la capital zacatecana y Guadalupe tambi\u00e9n se piensa en formatos m\u00e1s grandes, en el entendido que su empresa ve a Zacatecas como un estado en crecimiento.<\/p>\n<p>\u201cDesde 1983 y 1984 grupo Soriana tiene presencia comercial y econ\u00f3mica en Zacatecas, cuando se instal\u00f3 la primera tienda. De entonces a la fecha, se han abierto nuevos formatos; sin embargo, sentimos que todav\u00eda el estado da para mucho m\u00e1s y de ah\u00ed el inter\u00e9s de seguir creciendo\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00fan est\u00e1 por definirse el formato de tienda que se establecer\u00eda para iniciar operaciones en 2018<\/p>\n","protected":false},"author":37,"featured_media":48731,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-48729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soriana construir\u00e1 2 tiendas en Zacatecas -<\/title>\n<meta name=\"description\" content=\"Ricardo Mart\u00edn Bringas, director general de Organizaci\u00f3n Soriana, anunci\u00f3 que la empresa planea el desarrollo de dos tiendas en Zacatecas, aunque todav\u00eda no se define el formato, aunque la inversi\u00f3n planeada es de unos 250,000,000 de pesos para iniciar operaciones el pr\u00f3ximo a\u00f1o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soriana construir\u00e1 2 tiendas en Zacatecas -\" \/>\n<meta property=\"og:description\" content=\"Ricardo Mart\u00edn Bringas, director general de Organizaci\u00f3n Soriana, anunci\u00f3 que la empresa planea el desarrollo de dos tiendas en Zacatecas, aunque todav\u00eda no se define el formato, aunque la inversi\u00f3n planeada es de unos 250,000,000 de pesos para iniciar operaciones el pr\u00f3ximo a\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-10T15:32:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-10T15:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/soriana-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Rodr\u00edguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Rodr\u00edguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/\"},\"author\":{\"name\":\"Diego Rodr\u00edguez\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/46a73a1bfea462159370e0976b41af43\"},\"headline\":\"Soriana construir\u00e1 2 tiendas en Zacatecas\",\"datePublished\":\"2017-02-10T15:32:10+00:00\",\"dateModified\":\"2017-02-10T15:36:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/\"},\"wordCount\":289,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/soriana-2.jpg\",\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/\",\"name\":\"Soriana construir\u00e1 2 tiendas en Zacatecas -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/soriana-2.jpg\",\"datePublished\":\"2017-02-10T15:32:10+00:00\",\"dateModified\":\"2017-02-10T15:36:05+00:00\",\"description\":\"Ricardo Mart\u00edn Bringas, director general de Organizaci\u00f3n Soriana, anunci\u00f3 que la empresa planea el desarrollo de dos tiendas en Zacatecas, aunque todav\u00eda no se define el formato, aunque la inversi\u00f3n planeada es de unos 250,000,000 de pesos para iniciar operaciones el pr\u00f3ximo a\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/soriana-2.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/soriana-2.jpg\",\"width\":800,\"height\":533,\"caption\":\"A\u00fan est\u00e1 por definirse el formato de tienda que se establecer\u00eda para iniciar operaciones en 2018\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/soriana-construira-2-tiendas-en-zacatecas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soriana construir\u00e1 2 tiendas en Zacatecas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/46a73a1bfea462159370e0976b41af43\",\"name\":\"Diego Rodr\u00edguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g\",\"caption\":\"Diego Rodr\u00edguez\"},\"description\":\"Egresado de la Facultad de Estudios Superiores Acatl\u00e1n de la carrera en Comunicaci\u00f3n, con especialidad en medios escritos. Reportero del desaparecido peri\u00f3dico Nuestro M\u00e9xico, en donde cubri\u00f3 las fuentes delegacionales y Asamblea Legislativa. Tambi\u00e9n trabaj\u00f3 en la Coordinaci\u00f3n de Comunicaci\u00f3n Social en la delegaci\u00f3n \u00c1lvaro Obreg\u00f3n. Le gusta leer novelas y cuentos.\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/diegorodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soriana construir\u00e1 2 tiendas en Zacatecas -","description":"Ricardo Mart\u00edn Bringas, director general de Organizaci\u00f3n Soriana, anunci\u00f3 que la empresa planea el desarrollo de dos tiendas en Zacatecas, aunque todav\u00eda no se define el formato, aunque la inversi\u00f3n planeada es de unos 250,000,000 de pesos para iniciar operaciones el pr\u00f3ximo a\u00f1o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/","og_locale":"es_ES","og_type":"article","og_title":"Soriana construir\u00e1 2 tiendas en Zacatecas -","og_description":"Ricardo Mart\u00edn Bringas, director general de Organizaci\u00f3n Soriana, anunci\u00f3 que la empresa planea el desarrollo de dos tiendas en Zacatecas, aunque todav\u00eda no se define el formato, aunque la inversi\u00f3n planeada es de unos 250,000,000 de pesos para iniciar operaciones el pr\u00f3ximo a\u00f1o.","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2017-02-10T15:32:10+00:00","article_modified_time":"2017-02-10T15:36:05+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/soriana-2.jpg","type":"image\/jpeg"}],"author":"Diego Rodr\u00edguez","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Diego Rodr\u00edguez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/"},"author":{"name":"Diego Rodr\u00edguez","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/46a73a1bfea462159370e0976b41af43"},"headline":"Soriana construir\u00e1 2 tiendas en Zacatecas","datePublished":"2017-02-10T15:32:10+00:00","dateModified":"2017-02-10T15:36:05+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/"},"wordCount":289,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/soriana-2.jpg","articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/","name":"Soriana construir\u00e1 2 tiendas en Zacatecas -","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/soriana-2.jpg","datePublished":"2017-02-10T15:32:10+00:00","dateModified":"2017-02-10T15:36:05+00:00","description":"Ricardo Mart\u00edn Bringas, director general de Organizaci\u00f3n Soriana, anunci\u00f3 que la empresa planea el desarrollo de dos tiendas en Zacatecas, aunque todav\u00eda no se define el formato, aunque la inversi\u00f3n planeada es de unos 250,000,000 de pesos para iniciar operaciones el pr\u00f3ximo a\u00f1o.","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/soriana-2.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/soriana-2.jpg","width":800,"height":533,"caption":"A\u00fan est\u00e1 por definirse el formato de tienda que se establecer\u00eda para iniciar operaciones en 2018"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/soriana-construira-2-tiendas-en-zacatecas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Soriana construir\u00e1 2 tiendas en Zacatecas"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/46a73a1bfea462159370e0976b41af43","name":"Diego Rodr\u00edguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g","caption":"Diego Rodr\u00edguez"},"description":"Egresado de la Facultad de Estudios Superiores Acatl\u00e1n de la carrera en Comunicaci\u00f3n, con especialidad en medios escritos. Reportero del desaparecido peri\u00f3dico Nuestro M\u00e9xico, en donde cubri\u00f3 las fuentes delegacionales y Asamblea Legislativa. Tambi\u00e9n trabaj\u00f3 en la Coordinaci\u00f3n de Comunicaci\u00f3n Social en la delegaci\u00f3n \u00c1lvaro Obreg\u00f3n. Le gusta leer novelas y cuentos.","url":"https:\/\/centrourbano.com\/revista\/author\/diegorodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/48729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=48729"}],"version-history":[{"count":0,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/48729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/48731"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=48729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=48729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=48729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}