{"id":47368,"date":"2017-01-17T08:25:32","date_gmt":"2017-01-17T14:25:32","guid":{"rendered":"https:\/\/centrourbano.com\/?p=47368"},"modified":"2017-01-16T17:51:51","modified_gmt":"2017-01-16T23:51:51","slug":"empresas-del-ramo-automotriz-se-instalaran-slp","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/","title":{"rendered":"Empresas del ramo automotriz se instalar\u00e1n en SLP"},"content":{"rendered":"<p><em>Dos empresas son de capital alem\u00e1n y otra de origen franc\u00e9s<\/em><br \/>\n<!--more--><\/p>\n<p>El gobernador de San Lui Potos\u00ed, Juan Manuel Carreras, anunci\u00f3 la instalaci\u00f3n de 3 empresas ligadas al ramo automotriz, con una inversi\u00f3n conjunta de 346,000,000 de pesos, dos de las cuales son de capital alem\u00e1n y la otra de origen franc\u00e9s. <\/p>\n<p>El secretario de Desarrollo Econ\u00f3mico estatal, Gustavo Puente Orozco, dijo que esto ha sido posible por la promoci\u00f3n que se ha hecho de la entidad, tanto a inversionistas nacionales como extranjeros. <\/p>\n<p>\u201cEsto es una muestra clara de la confianza que tienen los empresarios de todas las latitudes en la entidad, sobre todo, en el talento y en la capacidad de la mano de obra de los potosinos, por lo que desde la administraci\u00f3n estatal se generar\u00e1n las condiciones necesarias para detonar el crecimiento integral de la entidad\u201d. <\/p>\n<p>Como ejemplo mencion\u00f3 el anunci\u00f3 de la armadora alemana BMW que reconfirm\u00f3 su inversi\u00f3n en el estado.<\/p>\n<p>Detall\u00f3 que las inversiones se ubicar\u00e1n en la Zona Industrial, Parque Tres Naciones y en World Trade Center I, con lo que se fortalece el cl\u00faster automotriz en la entidad. <\/p>\n<p>\u201cSon un referente en el sector de la proveedur\u00eda, espec\u00edficamente, para el sector automotriz que sigue siendo uno de las principales fortalezas en la entidad, para lo cual, las empresas conf\u00edan en los centros acad\u00e9micos, log\u00edsticos e industriales con que cuenta nuestro estado\u201d. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos empresas son de capital alem\u00e1n y otra de origen franc\u00e9s<\/p>\n","protected":false},"author":37,"featured_media":47369,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-47368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empresas del ramo automotriz se instalar\u00e1n en SLP -<\/title>\n<meta name=\"description\" content=\"El gobernador de San Lui Potos\u00ed, Juan Manuel Carreras, anunci\u00f3 la instalaci\u00f3n de 3 empresas ligadas al ramo automotriz, con una inversi\u00f3n conjunta de 346,000,000 de pesos, dos de las cuales son de capital alem\u00e1n y la otra de origen franc\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empresas del ramo automotriz se instalar\u00e1n en SLP -\" \/>\n<meta property=\"og:description\" content=\"El gobernador de San Lui Potos\u00ed, Juan Manuel Carreras, anunci\u00f3 la instalaci\u00f3n de 3 empresas ligadas al ramo automotriz, con una inversi\u00f3n conjunta de 346,000,000 de pesos, dos de las cuales son de capital alem\u00e1n y la otra de origen franc\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-17T14:25:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/slp.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Rodr\u00edguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Rodr\u00edguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/\"},\"author\":{\"name\":\"Diego Rodr\u00edguez\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/46a73a1bfea462159370e0976b41af43\"},\"headline\":\"Empresas del ramo automotriz se instalar\u00e1n en SLP\",\"datePublished\":\"2017-01-17T14:25:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/\"},\"wordCount\":254,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/slp.jpeg\",\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/\",\"name\":\"Empresas del ramo automotriz se instalar\u00e1n en SLP -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/slp.jpeg\",\"datePublished\":\"2017-01-17T14:25:32+00:00\",\"description\":\"El gobernador de San Lui Potos\u00ed, Juan Manuel Carreras, anunci\u00f3 la instalaci\u00f3n de 3 empresas ligadas al ramo automotriz, con una inversi\u00f3n conjunta de 346,000,000 de pesos, dos de las cuales son de capital alem\u00e1n y la otra de origen franc\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/slp.jpeg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/slp.jpeg\",\"width\":400,\"height\":300,\"caption\":\"Empresas del ramo automotriz se instalar\u00e1n en SLP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/empresas-del-ramo-automotriz-se-instalaran-slp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empresas del ramo automotriz se instalar\u00e1n en SLP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/46a73a1bfea462159370e0976b41af43\",\"name\":\"Diego Rodr\u00edguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g\",\"caption\":\"Diego Rodr\u00edguez\"},\"description\":\"Egresado de la Facultad de Estudios Superiores Acatl\u00e1n de la carrera en Comunicaci\u00f3n, con especialidad en medios escritos. Reportero del desaparecido peri\u00f3dico Nuestro M\u00e9xico, en donde cubri\u00f3 las fuentes delegacionales y Asamblea Legislativa. Tambi\u00e9n trabaj\u00f3 en la Coordinaci\u00f3n de Comunicaci\u00f3n Social en la delegaci\u00f3n \u00c1lvaro Obreg\u00f3n. Le gusta leer novelas y cuentos.\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/diegorodriguez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empresas del ramo automotriz se instalar\u00e1n en SLP -","description":"El gobernador de San Lui Potos\u00ed, Juan Manuel Carreras, anunci\u00f3 la instalaci\u00f3n de 3 empresas ligadas al ramo automotriz, con una inversi\u00f3n conjunta de 346,000,000 de pesos, dos de las cuales son de capital alem\u00e1n y la otra de origen franc\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/","og_locale":"es_ES","og_type":"article","og_title":"Empresas del ramo automotriz se instalar\u00e1n en SLP -","og_description":"El gobernador de San Lui Potos\u00ed, Juan Manuel Carreras, anunci\u00f3 la instalaci\u00f3n de 3 empresas ligadas al ramo automotriz, con una inversi\u00f3n conjunta de 346,000,000 de pesos, dos de las cuales son de capital alem\u00e1n y la otra de origen franc\u00e9s.","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2017-01-17T14:25:32+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/slp.jpeg","type":"image\/jpeg"}],"author":"Diego Rodr\u00edguez","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Diego Rodr\u00edguez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/"},"author":{"name":"Diego Rodr\u00edguez","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/46a73a1bfea462159370e0976b41af43"},"headline":"Empresas del ramo automotriz se instalar\u00e1n en SLP","datePublished":"2017-01-17T14:25:32+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/"},"wordCount":254,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/slp.jpeg","articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/","name":"Empresas del ramo automotriz se instalar\u00e1n en SLP -","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/slp.jpeg","datePublished":"2017-01-17T14:25:32+00:00","description":"El gobernador de San Lui Potos\u00ed, Juan Manuel Carreras, anunci\u00f3 la instalaci\u00f3n de 3 empresas ligadas al ramo automotriz, con una inversi\u00f3n conjunta de 346,000,000 de pesos, dos de las cuales son de capital alem\u00e1n y la otra de origen franc\u00e9s.","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/slp.jpeg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/slp.jpeg","width":400,"height":300,"caption":"Empresas del ramo automotriz se instalar\u00e1n en SLP"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/empresas-del-ramo-automotriz-se-instalaran-slp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Empresas del ramo automotriz se instalar\u00e1n en SLP"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/46a73a1bfea462159370e0976b41af43","name":"Diego Rodr\u00edguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d217565525df2df5d4e7265d47758506f41845ed9529510921a7625d8365789d?s=96&d=mm&r=g","caption":"Diego Rodr\u00edguez"},"description":"Egresado de la Facultad de Estudios Superiores Acatl\u00e1n de la carrera en Comunicaci\u00f3n, con especialidad en medios escritos. Reportero del desaparecido peri\u00f3dico Nuestro M\u00e9xico, en donde cubri\u00f3 las fuentes delegacionales y Asamblea Legislativa. Tambi\u00e9n trabaj\u00f3 en la Coordinaci\u00f3n de Comunicaci\u00f3n Social en la delegaci\u00f3n \u00c1lvaro Obreg\u00f3n. Le gusta leer novelas y cuentos.","url":"https:\/\/centrourbano.com\/revista\/author\/diegorodriguez\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/47368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=47368"}],"version-history":[{"count":0,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/47368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/47369"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=47368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=47368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=47368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}