{"id":470,"date":"2013-08-23T09:16:45","date_gmt":"2013-08-23T14:16:45","guid":{"rendered":"http:\/\/centrourbano.com\/revista\/?p=470"},"modified":"2023-03-30T00:52:47","modified_gmt":"2023-03-30T06:52:47","slug":"waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/","title":{"rendered":"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados"},"content":{"rendered":"<p><em>Con la nueva funci\u00f3n de Waze \u00abSupervivencia de Conductores\u00bb, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0<\/em><!--more--><\/p>\n<p>La nueva funci\u00f3n de Waze \u00abSupervivencia de Conductores\u00bb permite a los usuarios conocer con anticipaci\u00f3n los diversos cierres a la circulaci\u00f3n. Esto, a causa de manifestaciones, eventos, accidentes, cierres y bloqueos.<\/p>\n<p>La pr\u00f3xima edici\u00f3n del Marat\u00f3n de la Ciudad de M\u00e9xico 2013 es un ejemplo de ello. En dicho evento se espera la presencia de 20,000 participantes que correr\u00e1n por las principales avenidas de la ciudad. De esta manera, Waze podr\u00e1 anticipar los cierres viales.<\/p>\n<p>La <a href=\"https:\/\/www.waze.com\/es\/live-map\/\" target=\"_blank\" rel=\"noopener\">aplicaci\u00f3n gratuita de navegaci\u00f3n GPS<\/a> tiene como objetivo proporcionar a los usuarios la mejor ruta para llegar a sus destinos. Esto, tomando en cuenta los cierres vehiculares mencionados anteriormente. Los usuarios de Waze podr\u00e1n estar informados sobre el tr\u00e1fico en tiempo real; los mapas de la aplicaci\u00f3n ser\u00e1n actualizados constantemente durante los eventos en la ciudad.<\/p>\n<p>Con la funci\u00f3n \u00abSupervivencia de Conductores\u00bb, Waze se posiciona como una herramienta \u00fatil para aquellos que buscan evitar el tr\u00e1fico y los cierres. La aplicaci\u00f3n tambi\u00e9n considera los bloqueos de los maestros que se llevan a cabo en todo el pa\u00eds, lo que permite a los usuarios planificar sus rutas con anticipaci\u00f3n y evitar retrasos.<\/p>\n<p>Para aquellos que buscan una forma de evitar los cierres vehiculares y el tr\u00e1fico, Waze se presenta como una soluci\u00f3n \u00fatil y gratuita. Con su nueva funci\u00f3n \u00abSupervivencia de Conductores\u00bb, los usuarios pueden programar sus rutas con anticipaci\u00f3n y llegar a sus destinos de manera eficiente y sin contratiempos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la nueva funci\u00f3n de Waze \u00abSupervivencia de Conductores\u00bb, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0<\/p>\n","protected":false},"author":77,"featured_media":139104,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[6,82],"tags":[3278,15304],"class_list":["post-470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias","category-urbanismo","tag-cierres-vehiculares","tag-waze"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados<\/title>\n<meta name=\"description\" content=\"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados\" \/>\n<meta property=\"og:description\" content=\"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-23T14:16:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-30T06:52:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/descarga-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"G4A\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"G4A\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/\"},\"author\":{\"name\":\"G4A\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\"},\"headline\":\"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados\",\"datePublished\":\"2013-08-23T14:16:45+00:00\",\"dateModified\":\"2023-03-30T06:52:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/descarga-3.png\",\"keywords\":[\"cierres vehiculares\",\"Waze\"],\"articleSection\":[\"Tendencias\",\"Urbanismo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/\",\"name\":\"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/descarga-3.png\",\"datePublished\":\"2013-08-23T14:16:45+00:00\",\"dateModified\":\"2023-03-30T06:52:47+00:00\",\"description\":\"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/descarga-3.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/descarga-3.png\",\"width\":225,\"height\":225,\"caption\":\"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\",\"name\":\"G4A\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"caption\":\"G4A\"},\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/admin-g4a\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados","description":"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/","og_locale":"es_ES","og_type":"article","og_title":"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados","og_description":"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0","og_url":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2013-08-23T14:16:45+00:00","article_modified_time":"2023-03-30T06:52:47+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/descarga-3.png","type":"image\/png"}],"author":"G4A","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"G4A","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/"},"author":{"name":"G4A","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa"},"headline":"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados","datePublished":"2013-08-23T14:16:45+00:00","dateModified":"2023-03-30T06:52:47+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/descarga-3.png","keywords":["cierres vehiculares","Waze"],"articleSection":["Tendencias","Urbanismo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/","url":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/","name":"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/descarga-3.png","datePublished":"2013-08-23T14:16:45+00:00","dateModified":"2023-03-30T06:52:47+00:00","description":"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/descarga-3.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/descarga-3.png","width":225,"height":225,"caption":"Con la nueva funci\u00f3n de Waze, los usuarios pueden programar sus rutas con anticipaci\u00f3n y evitar cierres vehiculares inesperados\u00a0"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/waze-anade-funcion-para-evitar-cierres-vehiculares-inesperados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Waze a\u00f1ade funci\u00f3n para evitar cierres vehiculares inesperados"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa","name":"G4A","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","caption":"G4A"},"url":"https:\/\/centrourbano.com\/revista\/author\/admin-g4a\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":2,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"predecessor-version":[{"id":139105,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/470\/revisions\/139105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/139104"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}