{"id":163071,"date":"2026-07-22T14:46:24","date_gmt":"2026-07-22T20:46:24","guid":{"rendered":"https:\/\/centrourbano.com\/revista\/?p=163071"},"modified":"2026-07-22T14:46:24","modified_gmt":"2026-07-22T20:46:24","slug":"avalan-incorporar-vivienda-adecuada-ley-del-issste","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/","title":{"rendered":"Diputados avalan incorporar &#8216;vivienda adecuada&#8217; en la Ley del ISSSTE"},"content":{"rendered":"<p data-start=\"325\" data-end=\"705\"><em>La Comisi\u00f3n de Seguridad Social aprob\u00f3 una reforma para incorporar el <strong data-start=\"286\" data-end=\"319\">concepto de vivienda adecuada<\/strong> en la legislaci\u00f3n del ISSSTE, con el fin de armonizarla con la Constituci\u00f3n<\/em><!--more--><\/p>\n<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"325\" data-end=\"705\">La Comisi\u00f3n de Seguridad Social de la C\u00e1mara de Diputados aprob\u00f3 por unanimidad un dictamen para <strong>incorporar el concepto de vivienda adecuada<\/strong> en la Ley del Instituto de Seguridad y Servicios Sociales de los Trabajadores del Estado (ISSSTE). Con ello, la reforma busca <strong>armonizar la legislaci\u00f3n con la Constituci\u00f3n<\/strong> y fortalecer el reconocimiento del derecho humano a la vivienda.<\/p>\n<p data-start=\"707\" data-end=\"1087\">La propuesta modifica los art\u00edculos 4, 109, 169, 176 y 178 de la Ley del ISSSTE para incluir el calificativo de &#8216;adecuada&#8217; en las disposiciones relacionadas con este derecho. De acuerdo con el dictamen, el <strong>objetivo es reconocer que el acceso a la vivienda no se limita a un espacio f\u00edsico<\/strong>, sino que debe <strong>cumplir con condiciones m\u00ednimas que garanticen el bienestar<\/strong> de las personas.<\/p>\n<p data-start=\"1089\" data-end=\"1501\">No obstante, el alcance de la reforma se restringe al derecho humano a la vivienda. Por ello, el dictamen excluye las disposiciones que hacen referencia al Fondo de la Vivienda, ya que este constituye una figura jur\u00eddica integrada por las aportaciones que realizan las dependencias y entidades en favor de las personas trabajadoras, as\u00ed como por los bienes, derechos y rendimientos que generan esos recursos.<\/p>\n<p data-start=\"1503\" data-end=\"1712\">Asimismo, la propuesta mantiene<strong> sin cambios los art\u00edculos relacionados con los cr\u00e9ditos para vivienda<\/strong>, debido a que regulan mecanismos de financiamiento y no el reconocimiento del derecho humano a la vivienda.<\/p>\n<p data-start=\"1714\" data-end=\"2039\">Al presentar el dictamen, el presidente de la Comisi\u00f3n de Seguridad Social, Arturo Olivares Cerda, explic\u00f3 que la reforma responde a la necesidad de armonizar la Ley del ISSSTE con las modificaciones constitucionales y legales en materia de vivienda adecuada mediante la incorporaci\u00f3n de este concepto en distintos art\u00edculos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Seguridad Social aprob\u00f3 una reforma para incorporar el concepto de vivienda adecuada en la legislaci\u00f3n del ISSSTE, con el fin de armonizarla con la Constituci\u00f3n<\/p>\n","protected":false},"author":77,"featured_media":163072,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[12],"tags":[4574,352,4858],"class_list":["post-163071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vivienda","tag-camara-de-diputado","tag-issste","tag-vivienda-adecuada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diputados avalan incorporar &#039;vivienda adecuada&#039; en la Ley del ISSSTE<\/title>\n<meta name=\"description\" content=\"La Comisi\u00f3n de Seguridad Social aval\u00f3 incorporar el concepto de vivienda adecuada en la Ley del ISSSTE para armonizarla con la Constituci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diputados avalan incorporar &#039;vivienda adecuada&#039; en la Ley del ISSSTE\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n de Seguridad Social aval\u00f3 incorporar el concepto de vivienda adecuada en la Ley del ISSSTE para armonizarla con la Constituci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-22T20:46:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/800-diputados-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"G4A\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"G4A\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/\"},\"author\":{\"name\":\"G4A\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\"},\"headline\":\"Diputados avalan incorporar &#8216;vivienda adecuada&#8217; en la Ley del ISSSTE\",\"datePublished\":\"2026-07-22T20:46:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/\"},\"wordCount\":318,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/800-diputados-2.jpg\",\"keywords\":[\"C\u00e1mara de Diputado\",\"ISSSTE\",\"vivienda adecuada\"],\"articleSection\":[\"Vivienda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/\",\"name\":\"Diputados avalan incorporar 'vivienda adecuada' en la Ley del ISSSTE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/800-diputados-2.jpg\",\"datePublished\":\"2026-07-22T20:46:24+00:00\",\"description\":\"La Comisi\u00f3n de Seguridad Social aval\u00f3 incorporar el concepto de vivienda adecuada en la Ley del ISSSTE para armonizarla con la Constituci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/800-diputados-2.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/800-diputados-2.jpg\",\"width\":800,\"height\":800,\"caption\":\"Diputados avalan incorporar 'vivienda adecuada' en la Ley del ISSSTE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/vivienda\\\/avalan-incorporar-vivienda-adecuada-ley-del-issste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diputados avalan incorporar &#8216;vivienda adecuada&#8217; en la Ley del ISSSTE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\",\"name\":\"G4A\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"caption\":\"G4A\"},\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/admin-g4a\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diputados avalan incorporar 'vivienda adecuada' en la Ley del ISSSTE","description":"La Comisi\u00f3n de Seguridad Social aval\u00f3 incorporar el concepto de vivienda adecuada en la Ley del ISSSTE para armonizarla con la Constituci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/","og_locale":"es_ES","og_type":"article","og_title":"Diputados avalan incorporar 'vivienda adecuada' en la Ley del ISSSTE","og_description":"La Comisi\u00f3n de Seguridad Social aval\u00f3 incorporar el concepto de vivienda adecuada en la Ley del ISSSTE para armonizarla con la Constituci\u00f3n","og_url":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2026-07-22T20:46:24+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/800-diputados-2.jpg","type":"image\/jpeg"}],"author":"G4A","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"G4A","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/"},"author":{"name":"G4A","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa"},"headline":"Diputados avalan incorporar &#8216;vivienda adecuada&#8217; en la Ley del ISSSTE","datePublished":"2026-07-22T20:46:24+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/"},"wordCount":318,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/800-diputados-2.jpg","keywords":["C\u00e1mara de Diputado","ISSSTE","vivienda adecuada"],"articleSection":["Vivienda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/","url":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/","name":"Diputados avalan incorporar 'vivienda adecuada' en la Ley del ISSSTE","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/800-diputados-2.jpg","datePublished":"2026-07-22T20:46:24+00:00","description":"La Comisi\u00f3n de Seguridad Social aval\u00f3 incorporar el concepto de vivienda adecuada en la Ley del ISSSTE para armonizarla con la Constituci\u00f3n","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/800-diputados-2.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/800-diputados-2.jpg","width":800,"height":800,"caption":"Diputados avalan incorporar 'vivienda adecuada' en la Ley del ISSSTE"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/vivienda\/avalan-incorporar-vivienda-adecuada-ley-del-issste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Diputados avalan incorporar &#8216;vivienda adecuada&#8217; en la Ley del ISSSTE"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa","name":"G4A","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","caption":"G4A"},"url":"https:\/\/centrourbano.com\/revista\/author\/admin-g4a\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/163071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=163071"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/163071\/revisions"}],"predecessor-version":[{"id":163073,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/163071\/revisions\/163073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/163072"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=163071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=163071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=163071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}