{"id":162228,"date":"2026-06-10T13:49:39","date_gmt":"2026-06-10T19:49:39","guid":{"rendered":"https:\/\/centrourbano.com\/revista\/?p=162228"},"modified":"2026-06-10T13:49:39","modified_gmt":"2026-06-10T19:49:39","slug":"sedema-frena-hospedaje-flotante-xochimilco","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/","title":{"rendered":"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales"},"content":{"rendered":"<p><em data-start=\"493\" data-end=\"622\" data-is-only-node=\"\">El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco<\/em><!--more--><\/p>\n<p data-start=\"184\" data-end=\"530\">La Secretar\u00eda del Medio Ambiente (Sedema) de la Ciudad de M\u00e9xico inform\u00f3 que el <strong>proyecto de hospedaje flotante Akali<\/strong>, difundido en plataformas digitales como una experiencia de alojamiento en los canales de Xochimilco, <strong>no cuenta con autorizaci\u00f3n para operar dentro del \u00c1rea Natural Protegida<\/strong> (ANP) &#8216;Ejidos de Xochimilco y San Gregorio Atlapulco&#8217;.<\/p>\n<p data-start=\"532\" data-end=\"824\">La dependencia se\u00f1al\u00f3 que el servicio resulta<strong> incompatible con el Programa de Manejo vigente en la zona lacustre<\/strong>, el cual regula los usos permitidos dentro del ecosistema chinampero y restringe actividades que puedan afectar el equilibrio ambiental y el patrimonio agroecol\u00f3gico de la regi\u00f3n.<\/p>\n<p data-start=\"826\" data-end=\"1127\">El proyecto ofrec\u00eda pernocta a bordo de una trajinera adaptada como alojamiento tur\u00edstico, con espacios para descanso, cocina y estancia sobre los canales de Xochimilco. La experiencia se promocionaba como una alternativa de hospedaje temporal en contacto con el entorno natural y cultural de la zona.<\/p>\n<p data-start=\"1129\" data-end=\"1328\">Sin embargo, Sedema precis\u00f3 que c<strong>ualquier obra, actividad o servicio dentro del ANP requiere autorizaci\u00f3n<\/strong> expresa de la autoridad ambiental, permiso que no fue otorgado para este modelo de hospedaje.<\/p>\n<p data-start=\"1330\" data-end=\"1590\">Adem\u00e1s, record\u00f3 que la<strong> zona lacustre de Xochimilco cuenta con protecci\u00f3n ambiental desde 2006<\/strong> y opera bajo un Programa de Manejo publicado en 2018, instrumento que delimita las actividades permitidas en \u00e1reas chinamperas, agr\u00edcolas y de restauraci\u00f3n ecol\u00f3gica.<\/p>\n<p data-start=\"1592\" data-end=\"1887\">En este contexto, la dependencia indic\u00f3 que la Matriz de Manejo para la Zonificaci\u00f3n <strong>proh\u00edbe servicios tur\u00edsticos de alojamiento y construcciones<\/strong> con fines habitacionales dentro de las zonas de conservaci\u00f3n, debido a las afectaciones que podr\u00edan generar sobre canales, humedales y biodiversidad.<\/p>\n<blockquote>\n<p data-start=\"1889\" data-end=\"2165\">\u201cLa operaci\u00f3n de un alojamiento de esta naturaleza puede generar afectaciones al equilibrio ecol\u00f3gico, entre ellas la contaminaci\u00f3n de los canales y humedales, el deterioro de las estructuras chinamperas y la perturbaci\u00f3n de la fauna silvestre\u201d, se\u00f1al\u00f3 la Secretar\u00eda.<\/p>\n<\/blockquote>\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6985177c-4480-832e-bf2f-21ca568a8d4c-15\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6985177c-4480-832e-bf2f-21ca568a8d4c-15\" data-turn-id-container=\"request-6985177c-4480-832e-bf2f-21ca568a8d4c-15\" data-testid=\"conversation-turn-16\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"89c1f592-ed47-4df0-9469-0968c7f23c18\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p data-start=\"2408\" data-end=\"2734\" data-is-last-node=\"\" data-is-only-node=\"\">La dependencia advirti\u00f3 que este tipo de proyectos tambi\u00e9n comprometen la conservaci\u00f3n del paisaje lacustre y las actividades tradicionales que mantienen las comunidades de la zona chinampera, <strong>reconocida por la UNESCO como Patrimonio Mundial, Natural y Cultural de la Humanidad<\/strong>, adem\u00e1s de Humedal de Importancia Internacional.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco<\/p>\n","protected":false},"author":77,"featured_media":162229,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[82],"tags":[167,585],"class_list":["post-162228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urbanismo","tag-sedema","tag-xochimilco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales<\/title>\n<meta name=\"description\" content=\"El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales\" \/>\n<meta property=\"og:description\" content=\"El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-10T19:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"G4A\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"G4A\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/\"},\"author\":{\"name\":\"G4A\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\"},\"headline\":\"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales\",\"datePublished\":\"2026-06-10T19:49:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg\",\"keywords\":[\"Sedema\",\"Xochimilco\"],\"articleSection\":[\"Urbanismo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/\",\"name\":\"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg\",\"datePublished\":\"2026-06-10T19:49:39+00:00\",\"description\":\"El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg\",\"width\":800,\"height\":800,\"caption\":\"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/sedema-frena-hospedaje-flotante-xochimilco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\",\"name\":\"G4A\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"caption\":\"G4A\"},\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/admin-g4a\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales","description":"El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/","og_locale":"es_ES","og_type":"article","og_title":"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales","og_description":"El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco","og_url":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2026-06-10T19:49:39+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg","type":"image\/jpeg"}],"author":"G4A","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"G4A","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/"},"author":{"name":"G4A","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa"},"headline":"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales","datePublished":"2026-06-10T19:49:39+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg","keywords":["Sedema","Xochimilco"],"articleSection":["Urbanismo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/","url":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/","name":"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg","datePublished":"2026-06-10T19:49:39+00:00","description":"El gobierno capitalino alert\u00f3 sobre los impactos ambientales que podr\u00eda generar el hospedaje tur\u00edstico en canales de Xochimilco","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Sedema-frena-hospedaje-flotante-en-Xochimilco-por-incumplir-normas-ambientales.jpg","width":800,"height":800,"caption":"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/sedema-frena-hospedaje-flotante-xochimilco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Sedema frena hospedaje flotante en Xochimilco por incumplir normas ambientales"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa","name":"G4A","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","caption":"G4A"},"url":"https:\/\/centrourbano.com\/revista\/author\/admin-g4a\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/162228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=162228"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/162228\/revisions"}],"predecessor-version":[{"id":162230,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/162228\/revisions\/162230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/162229"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=162228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=162228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=162228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}