{"id":162223,"date":"2026-06-10T12:10:12","date_gmt":"2026-06-10T18:10:12","guid":{"rendered":"https:\/\/centrourbano.com\/revista\/?p=162223"},"modified":"2026-06-10T12:10:12","modified_gmt":"2026-06-10T18:10:12","slug":"crean-consejo-de-consulta-del-agua-cdmx","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/","title":{"rendered":"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX"},"content":{"rendered":"<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-69f14baa-22d0-83e8-b4cd-5d0037aaa4c3-13\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-69f14baa-22d0-83e8-b4cd-5d0037aaa4c3-13\" data-turn-id-container=\"request-69f14baa-22d0-83e8-b4cd-5d0037aaa4c3-13\" data-testid=\"conversation-turn-50\" data-scroll-anchor=\"false\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"ef53d150-52f2-47b2-9375-f3b656f82dac\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"139\" data-is-last-node=\"\" data-is-only-node=\"\"><em data-start=\"0\" data-end=\"139\" data-is-last-node=\"\" data-is-only-node=\"\">Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital<\/em><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<p><!--more--><\/p>\n<p class=\"isSelectedEnd\">Representantes de organismos t\u00e9cnicos, instituciones acad\u00e9micas, colegios especializados y autoridades locales formalizaron la integraci\u00f3n del <strong>Consejo de Consulta del Agua Ciudad de M\u00e9xico<\/strong>, un \u00f3rgano orientado a impulsar propuestas y proyectos relacionados con la gesti\u00f3n h\u00eddrica de la capital.<\/p>\n<p class=\"isSelectedEnd\">La iniciativa qued\u00f3 formalizada mediante la firma de una Carta de Intenci\u00f3n realizada en las instalaciones de la C\u00e1mara Mexicana de la Industria de la Construcci\u00f3n (CMIC) Ciudad de M\u00e9xico.<\/p>\n<p class=\"isSelectedEnd\">Entre las instituciones fundadoras del Consejo participan:<\/p>\n<ul data-spread=\"false\">\n<li>Asociaci\u00f3n Mexicana de Hidr\u00e1ulica (AMH)<\/li>\n<li>Instituto de Ingenier\u00eda de la UNAM<\/li>\n<li>Instituto de Geograf\u00eda de la UNAM<\/li>\n<li>Colegio de Ingenieros Civiles de M\u00e9xico (CICM)<\/li>\n<li>Colegio de Arquitectos de la Ciudad de M\u00e9xico<\/li>\n<li>Sociedad de Arquitectos Mexicanos<\/li>\n<li>Asociaci\u00f3n Nacional de Entidades de Agua y Saneamiento de M\u00e9xico (ANEAS)<\/li>\n<\/ul>\n<p class=\"isSelectedEnd\">Asimismo, la diputada Miriam Salda\u00f1a Ch\u00e1irez, integrante de la III Legislatura del Congreso de la Ciudad de M\u00e9xico, y la arquitecta Myriam Vilma Urz\u00faa Venegas, titular de la Secretar\u00eda de Gesti\u00f3n Integral de Riesgos y Protecci\u00f3n Civil de la Ciudad de M\u00e9xico, participaron en la formalizaci\u00f3n de la Carta de Intenci\u00f3n del nuevo organismo.<\/p>\n<h2>Agenda para gesti\u00f3n y recuperaci\u00f3n h\u00eddrica<\/h2>\n<p class=\"isSelectedEnd\">Como parte de los trabajos iniciales, el Consejo acord\u00f3 desarrollar cinco mesas de trabajo enfocadas en el <strong>rescate, conservaci\u00f3n y aprovechamiento de los r\u00edos Becerra y Tacubaya<\/strong>, bajo un esquema integral de gesti\u00f3n y aprovechamiento sustentable de recursos acu\u00edferos.<\/p>\n<p class=\"isSelectedEnd\">Adem\u00e1s, el organismo buscar\u00e1 <strong>fortalecer la coordinaci\u00f3n entre especialistas, academia, colegios<\/strong> y organismos t\u00e9cnicos para desarrollar propuestas de largo plazo en materia de infraestructura h\u00eddrica y sostenibilidad urbana.<\/p>\n<p class=\"isSelectedEnd\">Durante el encuentro, los organismos participantes destacaron la <strong>necesidad de impulsar mecanismos de colaboraci\u00f3n multidisciplinaria<\/strong> para atender los retos relacionados con el manejo, conservaci\u00f3n y aprovechamiento del agua en la capital del pa\u00eds.<\/p>\n<p>Con la creaci\u00f3n de este Consejo, las instituciones participantes<strong> buscan consolidar una agenda t\u00e9cnica enfocada en soluciones h\u00eddricas<\/strong> de largo plazo para la Ciudad de M\u00e9xico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital<\/p>\n","protected":false},"author":77,"featured_media":162226,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[82],"tags":[25597],"class_list":["post-162223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urbanismo","tag-consejo-de-consulta-del-agua-cdmx"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX<\/title>\n<meta name=\"description\" content=\"Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX\" \/>\n<meta property=\"og:description\" content=\"Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-10T18:10:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"G4A\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"G4A\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/\"},\"author\":{\"name\":\"G4A\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\"},\"headline\":\"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX\",\"datePublished\":\"2026-06-10T18:10:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg\",\"keywords\":[\"Consejo de Consulta del Agua CDMX\"],\"articleSection\":[\"Urbanismo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/\",\"name\":\"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg\",\"datePublished\":\"2026-06-10T18:10:12+00:00\",\"description\":\"Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg\",\"width\":800,\"height\":800,\"caption\":\"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/crean-consejo-de-consulta-del-agua-cdmx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/370fa0ba2d8dd5bde3fdb8b62ad360aa\",\"name\":\"G4A\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g\",\"caption\":\"G4A\"},\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/admin-g4a\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX","description":"Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/","og_locale":"es_ES","og_type":"article","og_title":"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX","og_description":"Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital","og_url":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2026-06-10T18:10:12+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg","type":"image\/jpeg"}],"author":"G4A","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"G4A","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/"},"author":{"name":"G4A","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa"},"headline":"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX","datePublished":"2026-06-10T18:10:12+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg","keywords":["Consejo de Consulta del Agua CDMX"],"articleSection":["Urbanismo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/","url":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/","name":"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg","datePublished":"2026-06-10T18:10:12+00:00","description":"Organismos t\u00e9cnicos, academia y autoridades impulsar\u00e1n mesas de trabajo para rescate de r\u00edos y gesti\u00f3n sustentable del agua en la capital","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Crean-Consejo-de-Consulta-del-Agua-para-atender-retos-hidricos-en-CDMX.jpg","width":800,"height":800,"caption":"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/crean-consejo-de-consulta-del-agua-cdmx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Crean Consejo de Consulta del Agua para atender retos h\u00eddricos en CDMX"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/370fa0ba2d8dd5bde3fdb8b62ad360aa","name":"G4A","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/932a97121b13d5de5bbd8193c6c83d3b92c9eda0f39623607d4280e7a5778d97?s=96&d=mm&r=g","caption":"G4A"},"url":"https:\/\/centrourbano.com\/revista\/author\/admin-g4a\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/162223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=162223"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/162223\/revisions"}],"predecessor-version":[{"id":162227,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/162223\/revisions\/162227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/162226"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=162223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=162223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=162223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}