{"id":158447,"date":"2025-10-27T14:06:04","date_gmt":"2025-10-27T20:06:04","guid":{"rendered":"https:\/\/centrourbano.com\/revista\/?p=158447"},"modified":"2025-10-27T14:06:04","modified_gmt":"2025-10-27T20:06:04","slug":"tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/","title":{"rendered":"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026"},"content":{"rendered":"<p><em>Autoridades supervisan las pruebas finales del tramo<\/em> Santa Fe\u2013Observatorio del Tren El Insurgente<em>; beneficiar\u00e1 a cinco millones de habitantes<\/em><!--more--><\/p>\n<p>Autoridades federales y estatales anunciaron que el tramo Santa Fe\u2013Observatorio del <a href=\"https:\/\/centrourbano.com\/revista\/?s=tren+interurbano\" target=\"_blank\" rel=\"noopener\">Tren Interurbano<\/a> <strong>El Insurgente entrar\u00e1 en operaci\u00f3n a finales de enero de 2026<\/strong>, una vez concluidas las pruebas t\u00e9cnicas y de certificaci\u00f3n que actualmente se desarrollan.<\/p>\n<p>As\u00ed lo anunciaron durante una visita de supervisi\u00f3n. El recorrido fue desde la estaci\u00f3n Santa Fe, con una escala en Vasco de Quiroga, y concluyeron en Observatorio, donde realizaron un trasbordo al Metro de la Ciudad de M\u00e9xico hacia la estaci\u00f3n Juanacatl\u00e1n.<\/p>\n<p>La presidenta de M\u00e9xico, Claudia Sheinbaum Pardo, anunci\u00f3 que encabez\u00f3 el recorrido de la <strong>tercera y \u00faltima etapa de pruebas del nuevo tramo<\/strong>, que conectar\u00e1 directamente al Valle de Toluca con la capital del pa\u00eds.<\/p>\n<p>Explic\u00f3 que el proceso de pruebas, que contempla la revisi\u00f3n de se\u00f1alizaci\u00f3n, sistemas de seguridad y certificaciones internacionales, se extender\u00e1 por <strong>alrededor de tres meses<\/strong>.<\/p>\n<blockquote><p>\u201cA partir de ahora inicia el periodo de pruebas que es muy importante porque requiere pruebas de la se\u00f1alizaci\u00f3n y la certificaci\u00f3n; eso significa que a finales de enero del 2026 ya se podr\u00e1 usar para toda la poblaci\u00f3n\u201d, detall\u00f3.<\/p><\/blockquote>\n<p>Por su parte, Delfina G\u00f3mez \u00c1lvarez, gobernadora del Estado de M\u00e9xico, destac\u00f3 que el proyecto forma parte de una estrategia integral para mejorar la movilidad y la calidad de vida de los mexiquenses.<\/p>\n<p>En tanto, Clara Brugada Molina se\u00f1al\u00f3 que el <strong>Complejo Observatorio <\/strong>se consolidar\u00e1 como la gran puerta poniente de la capital, al convertirse en un punto de conexi\u00f3n entre el Estado de M\u00e9xico y la Ciudad de M\u00e9xico. Agradeci\u00f3 adem\u00e1s el trabajo conjunto con los tres niveles de gobierno para <strong>fortalecer la infraestructura de movilidad metropolitana<\/strong>.<\/p>\n<p>Una vez concluida la obra el Tren Interurbano El Insurgente contar\u00e1 con una longitud total de 58 kil\u00f3metros y ofrecer\u00e1 un recorrido de aproximadamente 40 minutos entre Toluca y la Ciudad de M\u00e9xico. <strong>En total, tendr\u00e1 siete estaciones y 16 trenes,<\/strong> <strong>con una tarifa estimada de entre 15 y 90 pesos<\/strong>, seg\u00fan el trayecto. Se prev\u00e9 que atienda a 240 mil usuarios diarios y beneficie de manera directa a m\u00e1s de cinco millones de habitantes.<\/p>\n<p>Actualmente, el Tren El Insurgente opera un tramo de 50 kil\u00f3metros entre <strong>Zinacantepec y Santa Fe, con ocho trenes en funcionamiento<\/strong>. Desde su <strong>inauguraci\u00f3n en septiembre de 2023<\/strong>, ha transportado a m\u00e1s de 12.6 millones de pasajeros, consolid\u00e1ndose como uno de los proyectos ferroviarios m\u00e1s relevantes en materia de conectividad del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Autoridades supervisan las pruebas finales del tramo Santa Fe\u2013Observatorio del Tren El Insurgente; beneficiar\u00e1 a cinco millones de habitantes<\/p>\n","protected":false},"author":14,"featured_media":158448,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[14],"tags":[4365,255,25102],"class_list":["post-158447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construccion","tag-estacion-observatorio","tag-santa-fe","tag-tren-el-insurgente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026<\/title>\n<meta name=\"description\" content=\"Autoridades supervisan las pruebas finales del tramo Santa Fe\u2013Observatorio del Tren El Insurgente; beneficiar\u00e1 a cinco millones de habitantes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026\" \/>\n<meta property=\"og:description\" content=\"Autoridades supervisan las pruebas finales del tramo Santa Fe\u2013Observatorio del Tren El Insurgente; beneficiar\u00e1 a cinco millones de habitantes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T20:06:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n Centro Urbano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n Centro Urbano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n Centro Urbano\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c5c5ad19c284f8283dccf6cd07ea0aaa\"},\"headline\":\"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026\",\"datePublished\":\"2025-10-27T20:06:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/\"},\"wordCount\":451,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg\",\"keywords\":[\"Estaci\u00f3n Observatorio\",\"Santa Fe\",\"Tren 'El Insurgente'\"],\"articleSection\":[\"Construcci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/\",\"name\":\"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg\",\"datePublished\":\"2025-10-27T20:06:04+00:00\",\"description\":\"Autoridades supervisan las pruebas finales del tramo Santa Fe\u2013Observatorio del Tren El Insurgente; beneficiar\u00e1 a cinco millones de habitantes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg\",\"width\":800,\"height\":800,\"caption\":\"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/construccion\\\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c5c5ad19c284f8283dccf6cd07ea0aaa\",\"name\":\"Redacci\u00f3n Centro Urbano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n Centro Urbano\"},\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/editorial\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026","description":"Autoridades supervisan las pruebas finales del tramo Santa Fe\u2013Observatorio del Tren El Insurgente; beneficiar\u00e1 a cinco millones de habitantes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026","og_description":"Autoridades supervisan las pruebas finales del tramo Santa Fe\u2013Observatorio del Tren El Insurgente; beneficiar\u00e1 a cinco millones de habitantes","og_url":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2025-10-27T20:06:04+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n Centro Urbano","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Redacci\u00f3n Centro Urbano","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/"},"author":{"name":"Redacci\u00f3n Centro Urbano","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c5c5ad19c284f8283dccf6cd07ea0aaa"},"headline":"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026","datePublished":"2025-10-27T20:06:04+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/"},"wordCount":451,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg","keywords":["Estaci\u00f3n Observatorio","Santa Fe","Tren 'El Insurgente'"],"articleSection":["Construcci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/","url":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/","name":"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg","datePublished":"2025-10-27T20:06:04+00:00","description":"Autoridades supervisan las pruebas finales del tramo Santa Fe\u2013Observatorio del Tren El Insurgente; beneficiar\u00e1 a cinco millones de habitantes","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Tren-El-Insurgente_-tramo-Santa-Fe\u2013Observatorio-del-comenzara-operaciones-en-enero-de-2026.jpg","width":800,"height":800,"caption":"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/construccion\/tren-el-insurgente-tramo-santa-fe-observatorio-enero-de-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Tren El Insurgente: tramo Santa Fe\u2013Observatorio del comenzar\u00e1 operaciones en enero de 2026"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c5c5ad19c284f8283dccf6cd07ea0aaa","name":"Redacci\u00f3n Centro Urbano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g","caption":"Redacci\u00f3n Centro Urbano"},"url":"https:\/\/centrourbano.com\/revista\/author\/editorial\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/158447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=158447"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/158447\/revisions"}],"predecessor-version":[{"id":158449,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/158447\/revisions\/158449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/158448"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=158447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=158447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=158447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}