{"id":156875,"date":"2025-08-06T09:00:30","date_gmt":"2025-08-06T15:00:30","guid":{"rendered":"https:\/\/centrourbano.com\/revista\/?p=156875"},"modified":"2025-08-06T00:33:48","modified_gmt":"2025-08-06T06:33:48","slug":"mathias-goeritz-arquitecto-emocional","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/","title":{"rendered":"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional"},"content":{"rendered":"<p><em>\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz<\/em><!--more--><\/p>\n<p>Este 4 de agosto se cumplieron 35 a\u00f1os del fallecimiento de <strong>Mathias Goeritz<\/strong>, escultor, poeta, historiador del arte, arquitecto y pintor mexicano de origen alem\u00e1n, reconocido por ser el principal impulsor de la \u2018<strong>arquitectura emocional\u2019<\/strong>.<\/p>\n<p><strong>Werner Mathias Goeritz Brunner<\/strong> naci\u00f3 en Danzig, Alemania, el 4 de abril de 1915, y realiz\u00f3 sus estudios en la <strong>Escuela de Artes y Oficios de Charlottenburg<\/strong>, Berl\u00edn; y tambi\u00e9n obtuvo un doctorado en Filosof\u00eda e Historia del Arte en la<strong> Universidad Friedrich-Wilhelms<\/strong>.<\/p>\n<p>Posteriormente, abandon\u00f3 su pa\u00eds natal para residir, por varios a\u00f1os, en distintas partes de Europa y el Norte de \u00c1frica; hasta que, en 1949, fue invitado como maestro a la <strong>Escuela de Arquitectura de Guadalajara<\/strong> por el entonces rector de la misma, Ignacio D\u00edaz Morales, y tres a\u00f1os m\u00e1s tarde decidi\u00f3 establecerse permanentemente en la Ciudad de M\u00e9xico.<\/p>\n<p>En la capital mexicana fungi\u00f3 como docente en la <strong>Facultad de Arquitectura de la Universidad Nacional Aut\u00f3noma de M\u00e9xico<\/strong> (<strong>UNAM<\/strong>) y la <strong>Universidad Iberoamericana<\/strong>, y se encarg\u00f3 de la construcci\u00f3n de edificios y otros proyectos que, hasta hoy en d\u00eda, forman parte del paisaje urbano.<\/p>\n<h2><strong>La \u2018Arquitectura Emocional\u2019<\/strong><\/h2>\n<p>En 1954, <strong>Goeritz<\/strong> public\u00f3 el \u2018<strong>Manifiesto de Arquitectura Emocional\u2019<\/strong>, que detallaba el concepto que guiaba su obra, convirti\u00e9ndose en el principal precursor de esta nueva corriente arquitect\u00f3nica, la cual plantea el modo en que percibimos los espacios que habitamos y las funciones que desarrollamos dentro de ellos.<\/p>\n<p>El arquitecto utilizaba el <strong>color<\/strong>, la <strong>forma<\/strong> y la <strong>textura<\/strong> para provocar emociones a trav\u00e9s de sus creaciones, pues consideraba a la arquitectura como una obra de arte: \u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d.<\/p>\n<p>La <strong>arquitectura emocional<\/strong> conjuga elementos como el color, la iluminaci\u00f3n y el uso del agua para generar ambientes y agudizar los sentidos de las personas. Adem\u00e1s, en las obras pertenecientes a esta corriente, de acuerdo con arquitectos e historiadores del arte, existe la necesidad de un contenido simb\u00f3lico que provoque al espectador emociones por medio de formas, espacios y vol\u00famenes.<\/p>\n<p><strong>Goeritz<\/strong> quiso relacionar su experimento con la <strong>arquitectura cl\u00e1sica<\/strong> de catedrales y mezquitas, edificaciones abiertas a lo metaf\u00edsico, donde se busca de la ampliaci\u00f3n de los significados de vida.<\/p>\n<p>\u201cEn una \u00e9poca como la nuestra, con la falta de fe, \u00bfd\u00f3nde y c\u00f3mo puede ocurrir el encuentro con nosotros mismos? \u00bfSer\u00e1 posible que nuestra conciencia emotiva se extienda en otros espacios que no fueron destinados para ello y, en tal caso, qu\u00e9 situaci\u00f3n la detona? \u00bfSer\u00e1 que el espacio ritual contempor\u00e1neo dista mucho del religioso? \u00bfEs en los espacios sociales, culturales y espectaculares donde ha reca\u00eddo el peso de la recreaci\u00f3n humana?\u201d, expres\u00f3 en el <strong>manifiesto<\/strong><\/p>\n<h2><strong>Obras ic\u00f3nicas de Mathias Goeritz<\/strong><\/h2>\n<ul>\n<li><strong>Torres de Sat\u00e9lite<\/strong>\u2013 Creaci\u00f3n en colaboraci\u00f3n con Luis Barrag\u00e1n, consideradas un \u00edcono de la arquitectura moderna mexicana y un emblema urbano del Estado de M\u00e9xico.<\/li>\n<\/ul>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/satelite-3.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-156877 \" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/satelite-3.jpg\" alt=\"\" width=\"701\" height=\"468\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/satelite-3.jpg 750w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/satelite-3-300x200.jpg 300w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/a>\n<p><!--more--><\/p>\n<ul>\n<li><strong>El Eco<\/strong>\u2013 Museo experimental en la Ciudad de M\u00e9xico, dise\u00f1ado como un espacio para el &#8216;arte emocional&#8217; y hoy un referente cultural contempor\u00e1neo.<\/li>\n<\/ul>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/museo-experimental-el-eco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-156878\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/museo-experimental-el-eco.jpg\" alt=\"\" width=\"700\" height=\"524\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/museo-experimental-el-eco.jpg 1024w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/museo-experimental-el-eco-300x225.jpg 300w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/museo-experimental-el-eco-1000x749.jpg 1000w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/museo-experimental-el-eco-768x575.jpg 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a>\n<p><!--more--><\/p>\n<ul>\n<li><strong>El Animal del Pedregal<\/strong>\u2013 Escultura urbana integrada al paisaje volc\u00e1nico del sur de la Ciudad de M\u00e9xico.<\/li>\n<\/ul>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/animal.avif\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-156879\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/animal.avif\" alt=\"\" width=\"700\" height=\"560\" \/><\/a>\n<p><!--more--><\/p>\n<ul>\n<li><strong>La Corona del Pedregal<\/strong>\u2013 Estructura compuesta por cinco prismas que se levantan sobre piedra volc\u00e1nica, en el Espacio Escult\u00f3rico de la UNAM.<\/li>\n<\/ul>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/espacioescultorico001-819x1024-1.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-156880 \" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/espacioescultorico001-819x1024-1.jpg\" alt=\"\" width=\"489\" height=\"611\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/espacioescultorico001-819x1024-1.jpg 819w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/espacioescultorico001-819x1024-1-240x300.jpg 240w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/espacioescultorico001-819x1024-1-800x1000.jpg 800w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/espacioescultorico001-819x1024-1-768x960.jpg 768w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/><\/a>\n<p><!--more--><\/p>\n<ul>\n<li><strong>Ruta de la Amistad<\/strong>\u2013 Goeritz dise\u00f1\u00f3 La Ruta de la Amistad para la celebraci\u00f3n de los Juegos Ol\u00edmpicos de 1968 en la CDMX. Se trata de diversas esculturas abstractas y monumentales en las que participaron 18 artistas de 15 pa\u00edses.<\/li>\n<\/ul>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ritta-trejo-ruta-de-la-amistad-reloj-solar.avif\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-156881\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ritta-trejo-ruta-de-la-amistad-reloj-solar.avif\" alt=\"\" width=\"700\" height=\"409\" \/><\/a>\n","protected":false},"excerpt":{"rendered":"<p>\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz<\/p>\n","protected":false},"author":73,"featured_media":156876,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[81],"tags":[4943,16083,17357,5139],"class_list":["post-156875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitectura-2","tag-aniversario","tag-arquitectura-emocional","tag-fallecimiento","tag-mathias-goeritz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional<\/title>\n<meta name=\"description\" content=\"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional\" \/>\n<meta property=\"og:description\" content=\"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-06T15:00:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1333\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nannz_Hernandez\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/\"},\"author\":{\"name\":\"Fernanda Hern\u00e1ndez\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/9243fdb6807c0fed168f58712aef7db1\"},\"headline\":\"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional\",\"datePublished\":\"2025-08-06T15:00:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/\"},\"wordCount\":637,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg\",\"keywords\":[\"Aniversario\",\"Arquitectura emocional\",\"Fallecimiento\",\"Mathias Goeritz\"],\"articleSection\":[\"Arquitectura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/\",\"name\":\"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg\",\"datePublished\":\"2025-08-06T15:00:30+00:00\",\"description\":\"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg\",\"width\":1333,\"height\":1333,\"caption\":\"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/mathias-goeritz-arquitecto-emocional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/9243fdb6807c0fed168f58712aef7db1\",\"name\":\"Fernanda Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"caption\":\"Fernanda Hern\u00e1ndez\"},\"description\":\"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nannz_Hernandez\"],\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernanda-hernandez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional","description":"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/","og_locale":"es_ES","og_type":"article","og_title":"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional","og_description":"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz","og_url":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2025-08-06T15:00:30+00:00","og_image":[{"width":1333,"height":1333,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg","type":"image\/jpeg"}],"author":"Fernanda Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nannz_Hernandez","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernanda Hern\u00e1ndez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/"},"author":{"name":"Fernanda Hern\u00e1ndez","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/9243fdb6807c0fed168f58712aef7db1"},"headline":"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional","datePublished":"2025-08-06T15:00:30+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/"},"wordCount":637,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg","keywords":["Aniversario","Arquitectura emocional","Fallecimiento","Mathias Goeritz"],"articleSection":["Arquitectura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/","url":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/","name":"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg","datePublished":"2025-08-06T15:00:30+00:00","description":"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Mathias-Goeritz-35-an\u0303os-sin-el-arquitecto-del-\u2018sentimiento.jpg","width":1333,"height":1333,"caption":"\u201cS\u00f3lo recibiendo de la arquitectura emociones, el hombre puede volver a considerarla como un arte\u201d, declar\u00f3 Goeritz"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/mathias-goeritz-arquitecto-emocional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Mathias Goeritz: 35 a\u00f1os sin el arquitecto emocional"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/9243fdb6807c0fed168f58712aef7db1","name":"Fernanda Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","caption":"Fernanda Hern\u00e1ndez"},"description":"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Nannz_Hernandez"],"url":"https:\/\/centrourbano.com\/revista\/author\/fernanda-hernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/156875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=156875"}],"version-history":[{"count":1,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/156875\/revisions"}],"predecessor-version":[{"id":156882,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/156875\/revisions\/156882"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/156876"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=156875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=156875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=156875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}