{"id":141478,"date":"2023-07-28T09:00:32","date_gmt":"2023-07-28T15:00:32","guid":{"rendered":"https:\/\/centrourbano.com\/?p=141478"},"modified":"2023-07-27T22:34:24","modified_gmt":"2023-07-28T04:34:24","slug":"obras-santiago-calatrava","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/","title":{"rendered":"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava"},"content":{"rendered":"<p><em>A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999<\/em><!--more--><\/p>\n<p>Un d\u00eda como hoy, 28 de julio, pero de 1951, naci\u00f3, en Valencia, Espa\u00f1a, <a href=\"https:\/\/calatrava.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Santiago Calatrava Valls<\/strong><\/a>, uno de los arquitectos m\u00e1s relevantes de la actualidad a nivel mundial.<\/p>\n<p>El tambi\u00e9n ingeniero civil, escultor y dibujante, realiz\u00f3 sus estudios de Arquitectura en la <strong>Universidad Polit\u00e9cnica de Valencia<\/strong>, donde se gradu\u00f3 en 1974; y, posteriormente se traslad\u00f3 a Z\u00farich, Suiza, donde estableci\u00f3 su primer despacho y, en 1983, le fue adjudicada su primera obra relevante: la <strong>Estaci\u00f3n de Ferrocarril de Stadelhofen<\/strong>. Actualmente, adem\u00e1s de su primer despacho, cuenta con oficinas en Nueva York, Estados Unidos, y Doha, Catar.<\/p>\n<p><strong>Calatrava<\/strong> es considerado como un arquitecto especializado en grandes estructuras, y sus obras poseen influencias de Fernando Higueras, J\u00f8rn Utzon, Antoni Gaud\u00ed, y los estilos g\u00f3tico y romano.<\/p>\n<p>Adem\u00e1s, a lo largo de su trayectoria, ha recibido numerosos reconocimientos, como el <strong>Premio Pr\u00edncipe de Asturias de las Artes<\/strong> de 1999,\u200b los <strong>premios Nacionales de Arquitectura\u200b y de Ingenier\u00eda Civil<\/strong>, ambos en 2005, y el <strong>Premio Europeo de Arquitectura<\/strong> de 2015; adem\u00e1s de que ha sido nombrado <strong>Doctor Honoris<\/strong> <strong>Causa<\/strong> en 20 ocasiones, una de ellas por el Instituto Polit\u00e9cnico Nacional (IPN) en 2016.<\/p>\n<h2><strong>Obras representativas de Santiago Calatrava<\/strong><\/h2>\n<p>Algunos de los proyectos arquitect\u00f3nicos m\u00e1s importantes de <strong>Santiago Calatrava<\/strong> son:<\/p>\n<ul>\n<li><strong>Ciudad de las Artes y las Ciencias, Valencia (Espa\u00f1a)<\/strong><\/li>\n<\/ul>\n<p>Este complejo cultural, cient\u00edfico y de entretenimiento es una de las obras m\u00e1s conocidas de Calatrava y un \u00edcono de la ciudad de Valencia.<\/p>\n<p>Se compone del Museo de las Ciencias Pr\u00edncipe Felipe, un espacio que ofrece exposiciones interactivas sobre ciencia y tecnolog\u00eda; L\u2019Hemisf\u00e8ric, un cine digital 3D; el Palacio de las Artes Reina Sof\u00eda, que alberga importantes obras art\u00edsitcas; Oceanogr\u00e1fic, el acuario m\u00e1s grande de Europa; Umbracle, que cuenta con jardines con plantas t\u00edpicas del clima mediterr\u00e1neo; y el \u00c1gora, un espacio para eventos al aire libre.<\/p>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-scaled.jpeg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-141480 \" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-scaled.jpeg\" alt=\"santiago calatrava\" width=\"675\" height=\"450\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-scaled.jpeg 2560w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-300x200.jpeg 300w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-1000x667.jpeg 1000w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-768x512.jpeg 768w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-1536x1024.jpeg 1536w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/ciudad-de-las-artes-y-ciencias-2048x1365.jpeg 2048w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/a>\n<ul>\n<li><strong>Torre de Comunicaciones de Montjuic, Barcelona (Espa\u00f1a)<\/strong><\/li>\n<\/ul>\n<p>Calatrava desarroll\u00f3 esta torre de 136 metros de altura con motivo de los Juegos Ol\u00edmpicos de Barcelona en 1992.<\/p>\n<p>Est\u00e1 construida en acero y su base est\u00e1 decorada con una fuente de hormig\u00f3n recubierta de trencad\u00eds, un tipo de ornamentaci\u00f3n compuesta de mosaicos muy utilizada por el arquitecto Antoni Gaud\u00ed. Adem\u00e1s, su dise\u00f1o evoca la silueta de un deportista levantando la llama ol\u00edmpica.<\/p>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-scaled.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-141481 \" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-scaled.jpg\" alt=\"\" width=\"301\" height=\"449\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-scaled.jpg 1718w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-201x300.jpg 201w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-671x1000.jpg 671w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-768x1144.jpg 768w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-1031x1536.jpg 1031w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/torre-de-comunicaciones-1375x2048.jpg 1375w\" sizes=\"auto, (max-width: 301px) 100vw, 301px\" \/><\/a>\n<ul>\n<li><strong>Turning Torso, Malm\u00f6 (Suecia)<\/strong><\/li>\n<\/ul>\n<p>Esta torre de 190 metros de altura es uno de los edificios m\u00e1s altos e ic\u00f3nicos de Suecia, y, en 2005, fue reconocido como el Mejor Edificio Residencial del Mundo.<\/p>\n<p>Su dise\u00f1o se basa en una escultura de Calatrava, y su estructura se compone por varios cubos m\u00f3viles que parecen retorcerse seg\u00fan alcanzan altura. Y, adem\u00e1s de residencias, alberga restaurantes, tiendas y una galer\u00eda donde se explica c\u00f3mo fue su proceso de creaci\u00f3n.<\/p>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/turning-torso-1.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-141482 aligncenter\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/turning-torso-1.jpg\" alt=\"\" width=\"354\" height=\"450\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/turning-torso-1.jpg 1024w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/turning-torso-1-236x300.jpg 236w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/turning-torso-1-786x1000.jpg 786w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/turning-torso-1-768x977.jpg 768w\" sizes=\"auto, (max-width: 354px) 100vw, 354px\" \/><\/a>\n<ul>\n<li><strong>Quadracci Pavilion, Milwaukee (EUA)<\/strong><\/li>\n<\/ul>\n<p>Este proyecto, creado en 2001, es una expansi\u00f3n del Museo de Arte de Milwaukee, y destaca por su dise\u00f1o moderno y futurista.<\/p>\n<p>La peculiaridad de este pabell\u00f3n es que cuenta con una plataforma m\u00f3vil con forma de alas que se abre durante los d\u00edas soleados para crear sombra, y se cierra durante las noches.<\/p>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/quadracci.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-141483 \" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/quadracci.jpg\" alt=\"\" width=\"675\" height=\"450\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/quadracci.jpg 950w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/quadracci-300x200.jpg 300w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/quadracci-768x512.jpg 768w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/a>\n<ul>\n<li><strong>Creek Tower, Dub\u00e1i (Emiratos \u00c1rabes Unidos)<\/strong><\/li>\n<\/ul>\n<p>Actualmente en desarrollo, esta torre contar\u00e1 con una altura final de 1,300 metros, con lo que superar\u00e1 al rascacielos Burj Khalifa, la actual estructura m\u00e1s alta del mundo.<\/p>\n<p>Se espera que el desarrollo del proyecto finalice en 2030, para albergar al complejo tur\u00edstico y financiero Dubai Creek Harbour.<\/p>\n<a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Dubai-Creek-Harbour-with-Creek-Tower-1024x864-1.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-141484 \" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Dubai-Creek-Harbour-with-Creek-Tower-1024x864-1.jpg\" alt=\"\" width=\"533\" height=\"450\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Dubai-Creek-Harbour-with-Creek-Tower-1024x864-1.jpg 1024w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Dubai-Creek-Harbour-with-Creek-Tower-1024x864-1-300x253.jpg 300w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Dubai-Creek-Harbour-with-Creek-Tower-1024x864-1-1000x844.jpg 1000w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Dubai-Creek-Harbour-with-Creek-Tower-1024x864-1-768x648.jpg 768w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a>\n","protected":false},"excerpt":{"rendered":"<p>A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999<\/p>\n","protected":false},"author":73,"featured_media":141479,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[81],"tags":[20,2182,3491,23313,503,2423,9783,9670],"class_list":["post-141478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitectura-2","tag-arquitectura","tag-barcelona","tag-dubai","tag-milwuakee","tag-obras","tag-santiago-calatrava","tag-suecia","tag-valencia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava -<\/title>\n<meta name=\"description\" content=\"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999 Un d\u00eda como hoy,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava -\" \/>\n<meta property=\"og:description\" content=\"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999 Un d\u00eda como hoy,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T15:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nannz_Hernandez\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/\"},\"author\":{\"name\":\"Fernanda Hern\u00e1ndez\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c15dbe0eebafacb86ca1b55e3b2f84c6\"},\"headline\":\"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava\",\"datePublished\":\"2023-07-28T15:00:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/\"},\"wordCount\":633,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg\",\"keywords\":[\"arquitectura\",\"Barcelona\",\"Dubai\",\"Milwuakee\",\"Obras\",\"Santiago Calatrava\",\"Suecia\",\"Valencia\"],\"articleSection\":[\"Arquitectura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/\",\"name\":\"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg\",\"datePublished\":\"2023-07-28T15:00:32+00:00\",\"description\":\"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999 Un d\u00eda como hoy,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg\",\"width\":1500,\"height\":1278,\"caption\":\"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/arquitectura-2\\\/obras-santiago-calatrava\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c15dbe0eebafacb86ca1b55e3b2f84c6\",\"name\":\"Fernanda Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"caption\":\"Fernanda Hern\u00e1ndez\"},\"description\":\"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nannz_Hernandez\"],\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernanda-hernandez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava -","description":"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999 Un d\u00eda como hoy,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/","og_locale":"es_ES","og_type":"article","og_title":"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava -","og_description":"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999 Un d\u00eda como hoy,","og_url":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2023-07-28T15:00:32+00:00","og_image":[{"width":1500,"height":1278,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg","type":"image\/jpeg"}],"author":"Fernanda Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nannz_Hernandez","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernanda Hern\u00e1ndez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/"},"author":{"name":"Fernanda Hern\u00e1ndez","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c15dbe0eebafacb86ca1b55e3b2f84c6"},"headline":"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava","datePublished":"2023-07-28T15:00:32+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/"},"wordCount":633,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg","keywords":["arquitectura","Barcelona","Dubai","Milwuakee","Obras","Santiago Calatrava","Suecia","Valencia"],"articleSection":["Arquitectura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/","url":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/","name":"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava -","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg","datePublished":"2023-07-28T15:00:32+00:00","description":"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999 Un d\u00eda como hoy,","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Estas-son-las-5-obras-mas-importantes-de-Santiago-Calatrava.jpg","width":1500,"height":1278,"caption":"A lo largo de su trayectoria, Calatrava ha recibido numerosos reconocimientos, como el Premio Pr\u00edncipe de Asturias de las Artes, en 1999"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/arquitectura-2\/obras-santiago-calatrava\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Estas son las 5 obras m\u00e1s importantes de Santiago Calatrava"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c15dbe0eebafacb86ca1b55e3b2f84c6","name":"Fernanda Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","caption":"Fernanda Hern\u00e1ndez"},"description":"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Nannz_Hernandez"],"url":"https:\/\/centrourbano.com\/revista\/author\/fernanda-hernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/141478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=141478"}],"version-history":[{"count":2,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/141478\/revisions"}],"predecessor-version":[{"id":141486,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/141478\/revisions\/141486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/141479"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=141478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=141478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=141478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}