{"id":140992,"date":"2023-07-12T17:06:53","date_gmt":"2023-07-12T23:06:53","guid":{"rendered":"https:\/\/centrourbano.com\/?p=140992"},"modified":"2023-07-12T17:06:53","modified_gmt":"2023-07-12T23:06:53","slug":"nuevas-empresas-nearshoring","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/","title":{"rendered":"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos"},"content":{"rendered":"<p><em>La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero de empresas dedicadas al nearshoring<\/em><!--more--><\/p>\n<p>Especialistas estiman que el<strong> nearshoring se mantendr\u00e1 en aumento<\/strong>, tan es as\u00ed que piensan que <strong>para el 2025<\/strong>, <strong>M\u00e9xico albergar\u00e1 453 nuevas empresas<\/strong>. No obstante, los expertos indicaron que el pa\u00eds debe mejorar algunos temas para poder atraer m\u00e1s compa\u00f1\u00edas.<\/p>\n<p>Esos fueron algunos de los resultados que arroj\u00f3 una encuesta a miembros de la Asociaci\u00f3n Mexicana de Parques Industriales Privados (<a href=\"https:\/\/www.ampip.org.mx\/\" target=\"_blank\" rel=\"noopener\">AMPIP<\/a>), la cual tuvo como objetivo <strong>cuantificar y esclarecer la situaci\u00f3n del nearshoring<\/strong> en el pa\u00eds. Por ello, el ejercicio fue realizado con informaci\u00f3n obtenida de desarrolladores inmobiliarios miembros de la Asociaci\u00f3n.<\/p>\n<p>De manera que, los miembros indicaron que en los pr\u00f3ximos las <a href=\"https:\/\/centrourbano.com\/inmobiliario\/nearshoring-terrenos-industriales\/\" target=\"_blank\" rel=\"noopener\">empresas de este sector<\/a> aumentar\u00e1n a 453, de ese n\u00famero <strong>20% ser\u00e1n provenientes de China<\/strong>. Por lo tanto, la AMPIP se\u00f1al\u00f3 que en M\u00e9xico habr\u00e1 un crecimiento anual de 227 nuevas empresa; es decir, un crecimiento anual 9.1% por encima del periodo 2018-2022.<\/p>\n<p>Actualmente los parques industriales de la Asociaci\u00f3n concentran 20% de empresas nacionales y 80% de origen extranjero, de ellas el 97% tienen perfil exportador.<\/p>\n<h2>Retos que enfrenta el nearshoring en M\u00e9xico<\/h2>\n<p>Otro dato que se\u00f1al\u00f3 la encuesta son las caracter\u00edsticas que influyen en la elecci\u00f3n de empresa para elegir donde instalarse. Al respecto, los desarrolladores indicaron que las condiciones como perspectiva del <strong>mercado dom\u00e9stico y exterior<\/strong>, las condiciones comerciales y tratados (T-MEC) son gran influencia en la elecci\u00f3n. Adem\u00e1s de los<strong> servicios energ\u00e9ticos, de log\u00edstica, agua y de seguridad.<\/strong><\/p>\n<p>En ese sentido, los miembros de la AMPIP detallaron que <strong>M\u00e9xico debe trabajar para atender las limitantes<\/strong> en el abastecimiento de energ\u00eda el\u00e9ctrica limpia y ofrecer precios competitivos, drenaje y suministro de agua. Y en cuesti\u00f3n de autoridad, es necesario que los niveles de gobierno se comprometan a brindar seguridad p\u00fablica y mostrar eficiencia en tr\u00e1mites para facilitar el proceso de instalaci\u00f3n del nearshoring en el territorio.<\/p>\n<p>Estas afirmaciones surgen de la experiencia de los parques industriales encuestados, ya que el<strong> 91% de ellos reporta haber tenido afectaciones relacionadas con la oferta de energ\u00eda<\/strong> y <strong>63% relacionadas con la oferta de agua<\/strong>. Mientras que el 74% de los socios report\u00f3 haber sido afectado por la complejidad y velocidad de tr\u00e1mites; de acuerdo con los expertos, el \u00faltimo aspecto podr\u00eda ser solucionado a trav\u00e9s de una mejora regulatoria y normativa.<\/p>\n<p>Cabe se\u00f1alar que la Asociaci\u00f3n representa aproximadamente 430 parques industriales en 21 estados con m\u00e1s de 3,800 empresas instaladas. En cuanto al nivel de ocupaci\u00f3n, la AMPIP tienen el 3% del 97.9% para el cierre de 2022 y un crecimiento en inventarios del 30% en el mismo a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero de empresas dedicadas al nearshoring<\/p>\n","protected":false},"author":88,"featured_media":140995,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[23235,19243],"class_list":["post-140992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario","tag-asociacion-mexicana-de-parques-industriales-privados-ampip","tag-nearshoring"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos -<\/title>\n<meta name=\"description\" content=\"La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos -\" \/>\n<meta property=\"og:description\" content=\"La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-12T23:06:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/parque-industrial-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rebeca Romero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rebeca Romero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/\"},\"author\":{\"name\":\"Rebeca Romero\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/26b39ddd61b92a27f5f1f672c7e48260\"},\"headline\":\"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos\",\"datePublished\":\"2023-07-12T23:06:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/parque-industrial-2.jpg\",\"keywords\":[\"Asociaci\u00f3n Mexicana de Parques Industriales Privados (AMPIP)\",\"nearshoring\"],\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/\",\"name\":\"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/parque-industrial-2.jpg\",\"datePublished\":\"2023-07-12T23:06:53+00:00\",\"description\":\"La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/parque-industrial-2.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/parque-industrial-2.jpg\",\"width\":800,\"height\":800,\"caption\":\"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/nuevas-empresas-nearshoring\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/26b39ddd61b92a27f5f1f672c7e48260\",\"name\":\"Rebeca Romero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aee0068ae3cc041082e0e84a8258fe5ccc00a733f187bde73b0b40d86b892826?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aee0068ae3cc041082e0e84a8258fe5ccc00a733f187bde73b0b40d86b892826?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aee0068ae3cc041082e0e84a8258fe5ccc00a733f187bde73b0b40d86b892826?s=96&d=mm&r=g\",\"caption\":\"Rebeca Romero\"},\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/rebeca-romero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos -","description":"La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/","og_locale":"es_ES","og_type":"article","og_title":"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos -","og_description":"La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2023-07-12T23:06:53+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/parque-industrial-2.jpg","type":"image\/jpeg"}],"author":"Rebeca Romero","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Rebeca Romero","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/"},"author":{"name":"Rebeca Romero","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/26b39ddd61b92a27f5f1f672c7e48260"},"headline":"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos","datePublished":"2023-07-12T23:06:53+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/parque-industrial-2.jpg","keywords":["Asociaci\u00f3n Mexicana de Parques Industriales Privados (AMPIP)","nearshoring"],"articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/","name":"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos -","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/parque-industrial-2.jpg","datePublished":"2023-07-12T23:06:53+00:00","description":"La encuesta de la AMPIP se\u00f1al\u00f3 que si M\u00e9xico mejorar\u00e1 el abastecimiento de energ\u00eda el\u00e9ctrica, el drenaje y suministro de agua, podr\u00eda atraer mayor n\u00famero","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/parque-industrial-2.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/parque-industrial-2.jpg","width":800,"height":800,"caption":"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/nuevas-empresas-nearshoring\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Para el 2025, M\u00e9xico albergar\u00e1 453 nuevas empresas de nearshoring: expertos"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/26b39ddd61b92a27f5f1f672c7e48260","name":"Rebeca Romero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/aee0068ae3cc041082e0e84a8258fe5ccc00a733f187bde73b0b40d86b892826?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aee0068ae3cc041082e0e84a8258fe5ccc00a733f187bde73b0b40d86b892826?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aee0068ae3cc041082e0e84a8258fe5ccc00a733f187bde73b0b40d86b892826?s=96&d=mm&r=g","caption":"Rebeca Romero"},"url":"https:\/\/centrourbano.com\/revista\/author\/rebeca-romero\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/140992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=140992"}],"version-history":[{"count":2,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/140992\/revisions"}],"predecessor-version":[{"id":140997,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/140992\/revisions\/140997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/140995"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=140992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=140992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=140992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}