{"id":13377,"date":"2014-12-09T18:55:35","date_gmt":"2014-12-10T00:55:35","guid":{"rendered":"http:\/\/centrourbano.com\/?p=13377"},"modified":"2014-12-09T18:55:35","modified_gmt":"2014-12-10T00:55:35","slug":"instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/","title":{"rendered":"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales"},"content":{"rendered":"<p>&nbsp;<\/p>\n<ul>\n<li><em>Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n<\/em><\/li>\n<\/ul>\n<p><em>\u00a0<\/em><\/p>\n<ul>\n<li><em>Anuncia que las y los legisladores de la ALDF podr\u00e1n ser sometidos a ex\u00e1menes de evaluaci\u00f3n, psicom\u00e9tricos y poligr\u00e1ficos<\/em><\/li>\n<\/ul>\n<p><!--more--><\/p>\n<p><em>\u00a0<\/em><\/p>\n<p>El Jefe de Gobierno de la Ciudad de M\u00e9xico, Miguel \u00c1ngel Mancera Espinosa, instruy\u00f3 a los miembros de su Gabinete legal para que presenten, en el marco de la legalidad y a la brevedad posible, las versiones p\u00fablicas de sus declaraciones patrimoniales ante la Contralor\u00eda General del Distrito Federal.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante la presentaci\u00f3n del Sistema de Transparencia, Rendici\u00f3n de Cuentas, Fiscalizaci\u00f3n, Prevenci\u00f3n y Combate a la Corrupci\u00f3n, dio a conocer de la misma manera que, por un acuerdo voluntario solicitado por la Asamblea Legislativa del Distrito Federal (ALDF), las y los legisladores podr\u00e1n ser sometidos a ex\u00e1menes de evaluaci\u00f3n, psicom\u00e9tricos y poligr\u00e1ficos a efecto de sumarse a esta tarea.<\/p>\n<p>&nbsp;<\/p>\n<p>En el patio del Antiguo Palacio del Ayuntamiento, se\u00f1al\u00f3 que este tipo de ex\u00e1menes son los que los servidores p\u00fablicos de nuevo ingreso al Gobierno de la CDMX realizan y adelant\u00f3 que a partir del pr\u00f3ximo a\u00f1o lo presentar\u00e1n la totalidad de los mandos medios y superiores que conforman la administraci\u00f3n p\u00fablica local.<\/p>\n<p>En compa\u00f1\u00eda del presidente del Tribunal Superior de Justicia local (TSJDF), Edgar El\u00edas Azar, y del presidente de la Comisi\u00f3n de Gobierno de la ALDF, Manuel Granados, anunci\u00f3 la integraci\u00f3n de este sistema que contempla a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n que, sin duda, contribuir\u00e1 a avanzar en las 13 acciones estipuladas en el Plan para la Prevenci\u00f3n y el Combate a la misma.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEstamos claros que hay corrupci\u00f3n, pero no queremos dejarla pasar, tenemos que combatirla, tenemos que llevar a cabo acciones concretas\u201d, sostuvo el Ejecutivo local al asegurar que aunque se han dado pasos firmes en materia de transparencia y en el combate a la corrupci\u00f3n, \u201ceste es un mal que lacera, que\u00a0desgasta, que denigra, que corroe y que termina con muchas de las l\u00edneas de tejido social\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Destac\u00f3 que en lo que va del a\u00f1o se han sancionado a m\u00e1s de 3 mil 500 servidores p\u00fablicos y hay numerosas auditor\u00edas preventivas. Sin embargo,\u00a0\u00a0la CDMX por su tama\u00f1o y por la concentraci\u00f3n de tr\u00e1mites, requiere del compromiso de todos los sectores.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEn esta administraci\u00f3n creemos en la ciudadan\u00eda, en los lazos y en las l\u00edneas de acci\u00f3n de los ciudadanos, por eso hemos incrementado a m\u00e1s de 730 el n\u00famero de contralores ciudadanos y\u00a0\u00a0hemos puesto a disposici\u00f3n el aplicativo de denuncia ciudadana\u201d, indic\u00f3.<\/p>\n<p>Por ello, abund\u00f3, adem\u00e1s del redise\u00f1o de las leyes en esta capital y de la compactaci\u00f3n de casi 500 programas sociales a 160, se realizan otras acciones estrat\u00e9gicas para reducir los \u00edndices de corrupci\u00f3n. \u201cLo que planteamos con este nuevo sistema es una tarea colegiada en donde lograremos establecer, dise\u00f1ar, plantear pol\u00edticas p\u00fablicas en donde conjuntamente podemos intercambiar informaci\u00f3n, proyectos legislativos y compartir experiencias\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>En tanto, el contralor general de la CDMX, Hiram Almeida, enfatiz\u00f3 que a trav\u00e9s de este\u00a0Sistema de Transparencia, Rendici\u00f3n de Cuentas, Fiscalizaci\u00f3n, Prevenci\u00f3n y Combate a la Corrupci\u00f3n reunir\u00e1 a los sectores de la sociedad, los poderes Legislativo, Ejecutivo y Judicial, as\u00ed como a los \u00f3rganos encargados de la fiscalizaci\u00f3n en una nueva visi\u00f3n para generar soluciones directas y eficaces.\u00a0As\u00ed, se convocar\u00e1 a la sociedad civil a dise\u00f1ar y proponer las acciones 14 y 15 del Plan Anti Corrupci\u00f3n de la capital.<\/p>\n<p>&nbsp;<\/p>\n<p>Apunt\u00f3 que en el contexto del D\u00eda Contra la Corrupci\u00f3n, el Gobierno de la ciudad puede dar cuentas por medio de su Plan para la Prevenci\u00f3n y Combate contra la Corrupci\u00f3n puesto en marcha desde febrero de 2013 y del que entre sus resultados destacan las 2 mil 029 sanciones a servidores p\u00fablicos, la recepci\u00f3n de 31 mil 414 declaraciones patrimoniales y alrededor de 6 mil 225 evaluaciones de profesionalizaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Estuvieron presentes el procurador General de Justicia local, Rodolfo Fernando R\u00edos Garza; la comisionada del Instituto de Acceso a la Informaci\u00f3n y Protecci\u00f3n de Datos Personales, Elisa Bibiana Peralta Hern\u00e1ndez; y el director general de Transparencia Mexicana, Eduardo Boh\u00f3rquez, entre otros.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n \u00a0 Anuncia que las y los legisladores de la ALDF podr\u00e1n ser sometidos a ex\u00e1menes de evaluaci\u00f3n, psicom\u00e9tricos y poligr\u00e1ficos<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-13377","post","type-post","status-publish","format-standard","hentry","category-saladeprensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales  -<\/title>\n<meta name=\"description\" content=\"&nbsp; Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales  -\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-10T00:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/CU-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"91\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n Centro Urbano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n Centro Urbano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n Centro Urbano\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c5c5ad19c284f8283dccf6cd07ea0aaa\"},\"headline\":\"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales\",\"datePublished\":\"2014-12-10T00:55:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/\"},\"wordCount\":779,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"articleSection\":[\"Sala de Prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/\",\"name\":\"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"datePublished\":\"2014-12-10T00:55:35+00:00\",\"description\":\"&nbsp; Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/saladeprensa\\\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/c5c5ad19c284f8283dccf6cd07ea0aaa\",\"name\":\"Redacci\u00f3n Centro Urbano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n Centro Urbano\"},\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/editorial\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales  -","description":"&nbsp; Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/","og_locale":"es_ES","og_type":"article","og_title":"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales  -","og_description":"&nbsp; Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n","og_url":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2014-12-10T00:55:35+00:00","og_image":[{"width":350,"height":91,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/CU-logo.png","type":"image\/png"}],"author":"Redacci\u00f3n Centro Urbano","twitter_card":"summary_large_image","twitter_creator":"@CentroUrbano","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Redacci\u00f3n Centro Urbano","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/"},"author":{"name":"Redacci\u00f3n Centro Urbano","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c5c5ad19c284f8283dccf6cd07ea0aaa"},"headline":"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales","datePublished":"2014-12-10T00:55:35+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/"},"wordCount":779,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"articleSection":["Sala de Prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/","url":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/","name":"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales -","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"datePublished":"2014-12-10T00:55:35+00:00","description":"&nbsp; Se integra un nuevo sistema que conjuga a instancias, organismos de Gobierno, sociedad civil y la academia, en un frente com\u00fan contra la corrupci\u00f3n","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/saladeprensa\/instruye-mancera-a-su-gabinete-a-transparentar-sus-declaraciones-patrimoniales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Instruye Mancera a su Gabinete a transparentar sus declaraciones patrimoniales"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/c5c5ad19c284f8283dccf6cd07ea0aaa","name":"Redacci\u00f3n Centro Urbano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/15a789f894398c0f311f3a7a2ee28032bbc0483098539da66b6a045aa810bf35?s=96&d=mm&r=g","caption":"Redacci\u00f3n Centro Urbano"},"url":"https:\/\/centrourbano.com\/revista\/author\/editorial\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/13377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=13377"}],"version-history":[{"count":0,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/13377\/revisions"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=13377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=13377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=13377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}