{"id":109931,"date":"2020-07-30T09:00:46","date_gmt":"2020-07-30T14:00:46","guid":{"rendered":"https:\/\/centrourbano.com\/?p=109931"},"modified":"2020-07-30T12:36:15","modified_gmt":"2020-07-30T17:36:15","slug":"ingresos-de-fibra-prologis-aumentan-30-en-2t2020","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/","title":{"rendered":"Ingresos de Fibra Prologis aumentan 30% en 2T2020"},"content":{"rendered":"<p><em>En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico<\/em><\/p>\n<p><!--more--><\/p>\n<p>En d\u00edas recientes la <strong><a href=\"https:\/\/twitter.com\/Prologis\">Fibra Prologis<\/a><\/strong>, fideicomiso de inversi\u00f3n en bienes ra\u00edces de tipo industrial en M\u00e9xico, dio a conocer sus <strong>resultados financieros<\/strong> y operativos correspondientes al segundo trimestre del 2020 (<strong>2T2020<\/strong>).<\/p>\n<p>En primera instancia, report\u00f3 que <strong>los ingresos de la Fibra en el periodo del 2T2020 crecieron un 30.29% con respecto al 2T2019<\/strong>, pasaron de 938.81 millones de pesos (mdp) a 1,223.14 mdp.<\/p>\n<p>Explic\u00f3 que este se compone de 3 elementos , mismos que tuvieron variaciones distintas entre el 2019 y el 2020.<\/p>\n<ul>\n<li>Los <strong>ingresos por arrendamiento<\/strong> pasaron de <strong>831 a 1,096 mdp<\/strong>.<\/li>\n<li>Los ingresos por recuperaci\u00f3n de gastos de arrendamiento ascendieron 121 mdp en el 2T2020, mientras que en un a\u00f1o antes estos sumaron 88 mdp.<\/li>\n<li>Otros ingresos por arrendamiento bajaron de 18 mdp a una tercera parte: 6 mdp.<\/li>\n<\/ul>\n<p>Cabe se\u00f1alar que Prologis destac\u00f3 una serie de logros financieros en este segundo trimestre, dado el cr\u00edtico contexto econ\u00f3mico dejado por la crisis sanitaria.<\/p>\n<p>Mencion\u00f3 que la <strong><u>recolecci\u00f3n de la renta<\/u><\/strong> pas\u00f3 del 100.0% en el 2T2019 a un <strong>97.9%.<\/strong> Por su parte, la <strong><u>ocupaci\u00f3n al final<\/u><\/strong> del periodo fue de <strong>95.5%.<\/strong> Tuvo una leve ca\u00edda, de 1.1 puntos porcentuales, a\u00f1adi\u00f3 la Fibra, pero no fue por la crisis del Covid-19 sino porque fueron concluidos algunos contratos que ya ten\u00edan como fecha l\u00edmite este trimestre.<\/p>\n<p>El fideicomiso tambi\u00e9n enfatiz\u00f3 en que la <strong>renta neta efectiva en renovaciones creci\u00f3 13.2%<\/strong> y se <strong>complet\u00f3 la adquisici\u00f3n de activos por 8,824 millones de pesos<\/strong>.<\/p>\n<p>Los directivos de Prologis se congratularon de, pese a las desfavorables condiciones macroecon\u00f3micas, haber adquirido \u2018el principal parque log\u00edstico en la Ciudad de M\u00e9xico\u2019: Prologis Park Grande. As\u00ed mismo, indicaron que adquirieron dos inmuebles tipo \u2018Last Touch\u2019 al interior de zonas urbanas.<\/p>\n<h3>Prologis se declara \u2018cautelosamente optimista\u2019<\/h3>\n<p>En los \u00faltimos d\u00edas se ha venido presentando la informaci\u00f3n sobre el comportamiento financiero de las empresas y Fibras del sector inmobiliario. En estos se ha podido observar <strong>el fuerte impacto que la coyuntura sanitaria-econ\u00f3mica ha dejado en, sobre todo, las firmas hoteleras y de centros comerciales<\/strong>.<\/p>\n<p>Este no ha sido el caso de Fibra Prologis, la raz\u00f3n bien puede ser el giro industrial y log\u00edstico que caracteriza a la firma, giro que, como se ha podido observar, mostr\u00f3 la mayor resiliencia posible en todo el sector inmobiliario.<\/p>\n<p>Desde esa perspectiva, el director general de Prologis Property M\u00e9xico, Luis Guti\u00e9rrez, declar\u00f3 que <strong>hay un cauteloso optimismo en los pron\u00f3sticos sobre la din\u00e1mica que tendr\u00e1 la Fibra en los pr\u00f3ximos meses<\/strong>, todo esto sustentado en el papel que tienen los clientes de Prologis en la cadena de suministro de bienes b\u00e1sicos en el hogar y la nueva modalidad para hacerlos llegar a casa (comercio electr\u00f3nico).<\/p>\n<p>\u201cSi bien el COVID-19 contin\u00faa afectando la vida cotidiana, nuestro portafolio y clientes son factores clave para la cadena de suministro que sirven a la econom\u00eda del hogar.<\/p>\n<p>\u201cSeguimos siendo cautelosamente optimistas en nuestro pron\u00f3stico dada la adopci\u00f3n del comercio electr\u00f3nico y la operaciones de manufactura de \u201cnearshoring\u201d que avanzaron en la primera mitad del a\u00f1o y no muestran signos de desaceleraci\u00f3n.\u201d<\/p>\n<p>Finalmente, la Fibra se\u00f1al\u00f3 que, al 30 de junio de 2020, tiene en su portafolio 201 inmuebles destinados a la log\u00edstica y la manufactura en 6 mercados industriales de M\u00e9xico (CDMX, Guadalajara, Monterrey, Ciudad Ju\u00e1rez, Tijuana y Reynosa). Su \u00c1rea Bruta Rentable Total asciende a 3.6 millones de metros cuadrados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico<\/p>\n","protected":false},"author":75,"featured_media":109932,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[15],"tags":[18412,280,2368,19185,19186,14925,225,19189,19187,1684,19188,7768],"class_list":["post-109931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inmobiliario","tag-area-bruta-rentable","tag-fibra","tag-fibra-prologis","tag-informe-de-resultados","tag-ingresos-por-arrendamiento","tag-logistica","tag-manufactura","tag-mercados-industriales","tag-ocupacion-final","tag-prologis","tag-renta-neta","tag-resultados-financieros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ingresos de Fibra Prologis aumentan 30% en 2T2020<\/title>\n<meta name=\"description\" content=\"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingresos de Fibra Prologis aumentan 30% en 2T2020\" \/>\n<meta property=\"og:description\" content=\"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-30T14:00:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-30T17:36:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Prologis_Resultados-2T2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/TGarper\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/\"},\"author\":{\"name\":\"Antonio Garc\u00eda\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/aa4f77dc94bc74bbbbbd5bdf0ca96e0e\"},\"headline\":\"Ingresos de Fibra Prologis aumentan 30% en 2T2020\",\"datePublished\":\"2020-07-30T14:00:46+00:00\",\"dateModified\":\"2020-07-30T17:36:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/\"},\"wordCount\":610,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Prologis_Resultados-2T2020.jpg\",\"keywords\":[\"\u00c1rea Bruta Rentable\",\"Fibra\",\"Fibra Prologis\",\"informe de resultados\",\"ingresos por arrendamiento\",\"Log\u00edstica\",\"manufactura\",\"mercados industriales\",\"ocupaci\u00f3n final\",\"Prologis\",\"renta neta\",\"resultados financieros\"],\"articleSection\":[\"Inmobiliario\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/\",\"name\":\"Ingresos de Fibra Prologis aumentan 30% en 2T2020\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Prologis_Resultados-2T2020.jpg\",\"datePublished\":\"2020-07-30T14:00:46+00:00\",\"dateModified\":\"2020-07-30T17:36:15+00:00\",\"description\":\"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Prologis_Resultados-2T2020.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Prologis_Resultados-2T2020.jpg\",\"width\":1000,\"height\":500,\"caption\":\"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/inmobiliario\\\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ingresos de Fibra Prologis aumentan 30% en 2T2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/aa4f77dc94bc74bbbbbd5bdf0ca96e0e\",\"name\":\"Antonio Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68b7fcfc82d16a702310836698db1d823c3fb3b28e1f0938164455de47d96d82?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68b7fcfc82d16a702310836698db1d823c3fb3b28e1f0938164455de47d96d82?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68b7fcfc82d16a702310836698db1d823c3fb3b28e1f0938164455de47d96d82?s=96&d=mm&r=g\",\"caption\":\"Antonio Garc\u00eda\"},\"description\":\"Integrante del equipo editorial en Centro Urbano. Egresado de la carrera de Econom\u00eda (preespecialidad en Desarrollo Regional) en el IPN y de Matem\u00e1ticas Aplicadas y Computaci\u00f3n en la UNAM. Apasionado de los temas inherentes al desarrollo urbano-regional y estudios formales -e informales- sobre la ciudad y la econom\u00eda urbana.\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/caminante_en_la_ciudad\\\/?hl=es-la\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/TGarper\"],\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/antonio-garcia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ingresos de Fibra Prologis aumentan 30% en 2T2020","description":"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/","og_locale":"es_ES","og_type":"article","og_title":"Ingresos de Fibra Prologis aumentan 30% en 2T2020","og_description":"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico","og_url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2020-07-30T14:00:46+00:00","article_modified_time":"2020-07-30T17:36:15+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Prologis_Resultados-2T2020.jpg","type":"image\/jpeg"}],"author":"Antonio Garc\u00eda","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/TGarper","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Antonio Garc\u00eda","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/"},"author":{"name":"Antonio Garc\u00eda","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/aa4f77dc94bc74bbbbbd5bdf0ca96e0e"},"headline":"Ingresos de Fibra Prologis aumentan 30% en 2T2020","datePublished":"2020-07-30T14:00:46+00:00","dateModified":"2020-07-30T17:36:15+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/"},"wordCount":610,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Prologis_Resultados-2T2020.jpg","keywords":["\u00c1rea Bruta Rentable","Fibra","Fibra Prologis","informe de resultados","ingresos por arrendamiento","Log\u00edstica","manufactura","mercados industriales","ocupaci\u00f3n final","Prologis","renta neta","resultados financieros"],"articleSection":["Inmobiliario"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/","url":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/","name":"Ingresos de Fibra Prologis aumentan 30% en 2T2020","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Prologis_Resultados-2T2020.jpg","datePublished":"2020-07-30T14:00:46+00:00","dateModified":"2020-07-30T17:36:15+00:00","description":"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Prologis_Resultados-2T2020.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Prologis_Resultados-2T2020.jpg","width":1000,"height":500,"caption":"En el informe de resultados del 2T2020 de Prologis, la Fibra dio cuenta de la solidez de sus finanzas y el aumento de la demanda de espacio log\u00edstico"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/inmobiliario\/ingresos-de-fibra-prologis-aumentan-30-en-2t2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Ingresos de Fibra Prologis aumentan 30% en 2T2020"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/aa4f77dc94bc74bbbbbd5bdf0ca96e0e","name":"Antonio Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68b7fcfc82d16a702310836698db1d823c3fb3b28e1f0938164455de47d96d82?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68b7fcfc82d16a702310836698db1d823c3fb3b28e1f0938164455de47d96d82?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68b7fcfc82d16a702310836698db1d823c3fb3b28e1f0938164455de47d96d82?s=96&d=mm&r=g","caption":"Antonio Garc\u00eda"},"description":"Integrante del equipo editorial en Centro Urbano. Egresado de la carrera de Econom\u00eda (preespecialidad en Desarrollo Regional) en el IPN y de Matem\u00e1ticas Aplicadas y Computaci\u00f3n en la UNAM. Apasionado de los temas inherentes al desarrollo urbano-regional y estudios formales -e informales- sobre la ciudad y la econom\u00eda urbana.","sameAs":["https:\/\/www.instagram.com\/caminante_en_la_ciudad\/?hl=es-la","https:\/\/x.com\/https:\/\/twitter.com\/TGarper"],"url":"https:\/\/centrourbano.com\/revista\/author\/antonio-garcia\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/109931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=109931"}],"version-history":[{"count":2,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/109931\/revisions"}],"predecessor-version":[{"id":109934,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/109931\/revisions\/109934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/109932"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=109931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=109931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=109931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}