{"id":101000,"date":"2020-01-03T09:37:26","date_gmt":"2020-01-03T15:37:26","guid":{"rendered":"https:\/\/centrourbano.com\/?p=101000"},"modified":"2020-01-03T09:37:33","modified_gmt":"2020-01-03T15:37:33","slug":"programa-verificacion-vehicular","status":"publish","type":"post","link":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/","title":{"rendered":"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020"},"content":{"rendered":"\n<p><em>De acuerdo con la Sedema, estos son los lineamientos del<\/em> <em>Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX<\/em><\/p>\n\n\n\n<p>La <strong>Secretar\u00eda del Medio Ambiente (Sedema) de\nla Ciudad de M\u00e9xico<\/strong> anunci\u00f3 los lineamientos del <strong>Programa de Verificaci\u00f3n Vehicular<\/strong> que aplicar\u00e1 en el primer semestre de 2020:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Expedici\u00f3n de holograma 00<\/strong><\/li><\/ul>\n\n\n\n<p>La dependencia detall\u00f3 que \u00e9sta depender\u00e1 de las emisiones y el rendimiento de combustible que presenten los automotores. El <strong>listado de automotores<\/strong> que cumplen con las caracter\u00edsticas necesarias para obtener dicho holograma, por una o dos ocasiones, puede ser consultado en la p\u00e1gina web de la <strong><a href=\"https:\/\/www.sedema.cdmx.gob.mx\/storage\/app\/media\/CATALOGO%20VEHICULAR%20311219.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Sedema (se abre en una nueva pesta\u00f1a)\">Sedema<\/a><\/strong>. <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Tarifas de verificaci\u00f3n y multas <\/strong><\/li><\/ul>\n\n\n\n<p>El servicio de verificaci\u00f3n y las multas\npor verificaci\u00f3n extempor\u00e1nea, por circular en horario restringido, por no\nportar verificaci\u00f3n vehicular vigente o por circular emitiendo contaminaci\u00f3n\nostensible, se rigen por\nla <strong>UMA (Unidad de Medida de\nActualizaci\u00f3n)<\/strong>; la cual se actualizar\u00e1 en la segunda quincena de enero e\niniciar\u00e1 su aplicaci\u00f3n el primero de febrero.<\/p>\n\n\n\n<p>La indexaci\u00f3n\nactual, con equivalencia en pesos, es:<\/p>\n\n\n\n<p>&#8211; <strong>Servicio de verificaci\u00f3n vehicular: 5.625\n(UMA) m\u00e1s IVA = 551 pesos<\/strong><\/p>\n\n\n\n<p><strong>&#8211; Multas: 20 (UMAS) = 1,690 pesos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Veh\u00edculos H\u00edbridos<\/strong><\/li><\/ul>\n\n\n\n<p>Los veh\u00edculos\ncuya tecnolog\u00eda no permita la\npropulsi\u00f3n al utilizar s\u00f3lo el motor el\u00e9ctrico, <strong>no podr\u00e1n<\/strong><strong>obtener el holograma exento<\/strong>. Lo anterior, debido a que este tipo de veh\u00edculos dependen del motor de combusti\u00f3n\ninterna para su operaci\u00f3n; lo cual propicia que el rendimiento de los mismos no\nsea significativamente mayor al de sus similares a gasolina.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Taxis<\/strong><\/li><\/ul>\n\n\n\n<p>Los taxis\nnuevos que cumplan con\nlos requisitos, podr\u00e1n obtener el <strong>holograma\n00.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Verificentros<\/strong><\/li><\/ul>\n\n\n\n<p>Los centros de verificaci\u00f3n de emisiones vehiculares en la Ciudad de M\u00e9xico iniciar\u00e1n operaciones el <strong>6 de enero de 2020,<\/strong> despu\u00e9s de realizar el mantenimiento y actualizaci\u00f3n de sistemas inform\u00e1ticos que soportan la operaci\u00f3n de los equipos para otorgar el <strong>holograma 00.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/calendario_verificacion.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"548\" height=\"522\" src=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/calendario_verificacion.jpg\" alt=\"\" class=\"wp-image-101006\" srcset=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/calendario_verificacion.jpg 548w, https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/calendario_verificacion-300x286.jpg 300w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX La Secretar\u00eda del Medio Ambiente (Sedema) de la Ciudad de M\u00e9xico anunci\u00f3 los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre de 2020: Expedici\u00f3n de holograma [&hellip;]<\/p>\n","protected":false},"author":73,"featured_media":101001,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[82],"tags":[17163,6156,17164,11497],"class_list":["post-101000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urbanismo","tag-lineamientos","tag-urbanismo","tag-verificacion-2020","tag-verificacion-vehicular"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020<\/title>\n<meta name=\"description\" content=\"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020\" \/>\n<meta property=\"og:description\" content=\"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro Urbano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcentrourbano\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-03T15:37:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-03T15:37:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"813\" \/>\n\t<meta property=\"og:image:height\" content=\"527\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nannz_Hernandez\" \/>\n<meta name=\"twitter:site\" content=\"@CentroUrbano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/\"},\"author\":{\"name\":\"Fernanda Hern\u00e1ndez\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/9243fdb6807c0fed168f58712aef7db1\"},\"headline\":\"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020\",\"datePublished\":\"2020-01-03T15:37:26+00:00\",\"dateModified\":\"2020-01-03T15:37:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/\"},\"wordCount\":340,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg\",\"keywords\":[\"Lineamientos\",\"Urbanismo\",\"Verificaci\u00f3n 2020\",\"verificaci\u00f3n vehicular\"],\"articleSection\":[\"Urbanismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/\",\"name\":\"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg\",\"datePublished\":\"2020-01-03T15:37:26+00:00\",\"dateModified\":\"2020-01-03T15:37:33+00:00\",\"description\":\"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg\",\"width\":813,\"height\":527,\"caption\":\"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/urbanismo\\\/programa-verificacion-vehicular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#website\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"name\":\"Centro Urbano\",\"description\":\"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#organization\",\"name\":\"Centro Urbano\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"contentUrl\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/wp-content\\\/uploads\\\/web_CU_logo-1.png\",\"width\":350,\"height\":91,\"caption\":\"Centro Urbano\"},\"image\":{\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/portalcentrourbano\",\"https:\\\/\\\/x.com\\\/CentroUrbano\",\"https:\\\/\\\/www.instagram.com\\\/centro_urbano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/centro-urbano\\\/\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/portalcentrourbano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/#\\\/schema\\\/person\\\/9243fdb6807c0fed168f58712aef7db1\",\"name\":\"Fernanda Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g\",\"caption\":\"Fernanda Hern\u00e1ndez\"},\"description\":\"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nannz_Hernandez\"],\"url\":\"https:\\\/\\\/centrourbano.com\\\/revista\\\/author\\\/fernanda-hernandez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020","description":"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/","og_locale":"es_ES","og_type":"article","og_title":"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020","og_description":"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX","og_url":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/","og_site_name":"Centro Urbano","article_publisher":"https:\/\/www.facebook.com\/portalcentrourbano","article_published_time":"2020-01-03T15:37:26+00:00","article_modified_time":"2020-01-03T15:37:33+00:00","og_image":[{"width":813,"height":527,"url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg","type":"image\/jpeg"}],"author":"Fernanda Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nannz_Hernandez","twitter_site":"@CentroUrbano","twitter_misc":{"Escrito por":"Fernanda Hern\u00e1ndez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#article","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/"},"author":{"name":"Fernanda Hern\u00e1ndez","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/9243fdb6807c0fed168f58712aef7db1"},"headline":"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020","datePublished":"2020-01-03T15:37:26+00:00","dateModified":"2020-01-03T15:37:33+00:00","mainEntityOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/"},"wordCount":340,"commentCount":0,"publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg","keywords":["Lineamientos","Urbanismo","Verificaci\u00f3n 2020","verificaci\u00f3n vehicular"],"articleSection":["Urbanismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/","url":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/","name":"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020","isPartOf":{"@id":"https:\/\/centrourbano.com\/revista\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#primaryimage"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#primaryimage"},"thumbnailUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg","datePublished":"2020-01-03T15:37:26+00:00","dateModified":"2020-01-03T15:37:33+00:00","description":"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX","breadcrumb":{"@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#primaryimage","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/Lo-que-debes-saber-del-Programa-de-Verificaci\u00f3n-Vehicular-2020.jpg","width":813,"height":527,"caption":"De acuerdo con la Sedema, estos son los lineamientos del Programa de Verificaci\u00f3n Vehicular que aplicar\u00e1 en el primer semestre del 2020 en la CDMX"},{"@type":"BreadcrumbList","@id":"https:\/\/centrourbano.com\/revista\/urbanismo\/programa-verificacion-vehicular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centrourbano.com\/revista\/"},{"@type":"ListItem","position":2,"name":"Lo que debes saber del Programa de Verificaci\u00f3n Vehicular 2020"}]},{"@type":"WebSite","@id":"https:\/\/centrourbano.com\/revista\/#website","url":"https:\/\/centrourbano.com\/revista\/","name":"Centro Urbano","description":"Medio especializado en los sectores vivienda, inmobiliario, construcci\u00f3n, arquitectura y urbanismo.","publisher":{"@id":"https:\/\/centrourbano.com\/revista\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centrourbano.com\/revista\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/centrourbano.com\/revista\/#organization","name":"Centro Urbano","url":"https:\/\/centrourbano.com\/revista\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/","url":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","contentUrl":"https:\/\/centrourbano.com\/revista\/wp-content\/uploads\/web_CU_logo-1.png","width":350,"height":91,"caption":"Centro Urbano"},"image":{"@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcentrourbano","https:\/\/x.com\/CentroUrbano","https:\/\/www.instagram.com\/centro_urbano\/","https:\/\/www.linkedin.com\/company\/centro-urbano\/","http:\/\/www.youtube.com\/user\/portalcentrourbano"]},{"@type":"Person","@id":"https:\/\/centrourbano.com\/revista\/#\/schema\/person\/9243fdb6807c0fed168f58712aef7db1","name":"Fernanda Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9471831fb0a24eae9d32d826a7cb8ef07c34a41520aca1a0ab1f5c0903ba49b9?s=96&d=mm&r=g","caption":"Fernanda Hern\u00e1ndez"},"description":"Reportera y redactora en Centro Urbano. Soy egresada de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Facultad de Ciencias Pol\u00edticas y Sociales (UNAM). Me interesa la cultura, el urbanismo y la arquitectura. Amante del mundo digital, el cine, la m\u00fasica, la lectura y la escritura.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Nannz_Hernandez"],"url":"https:\/\/centrourbano.com\/revista\/author\/fernanda-hernandez\/"}]}},"_links":{"self":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/101000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/users\/73"}],"replies":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/comments?post=101000"}],"version-history":[{"count":2,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/101000\/revisions"}],"predecessor-version":[{"id":101032,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/posts\/101000\/revisions\/101032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media\/101001"}],"wp:attachment":[{"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/media?parent=101000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/categories?post=101000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centrourbano.com\/revista\/wp-json\/wp\/v2\/tags?post=101000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}